{"id":35152,"date":"2022-03-17T07:59:52","date_gmt":"2022-03-17T10:59:52","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=35152"},"modified":"2022-03-29T00:43:55","modified_gmt":"2022-03-29T03:43:55","slug":"marica-registra-mais-03-mortes-pela-covid-19","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/03\/17\/marica-registra-mais-03-mortes-pela-covid-19\/","title":{"rendered":"Maric\u00e1 registra mais 03 mortes\u00a0pela Covid-19"},"content":{"rendered":"\n<p><br>O munic\u00edpio de Maric\u00e1&nbsp;registrou mais 03 mortes pela Covid-19, segundo a Secretaria Municipal de Sa\u00fade, atrav\u00e9s do boletim epidemiol\u00f3gico divulgado na noite desta quarta-feira (16).<\/p>\n\n\n\n<p>Ainda segundo o boletim, a cidade registrou 05 casos positivos da doen\u00e7a em uma semana.<\/p>\n\n\n\n<p>O munic\u00edpio chegou a 93,3% da popula\u00e7\u00e3o com a vacina\u00e7\u00e3o completa contra o novo coronav\u00edrus. A cidade segue com 20 \u00f3bitos em an\u00e1lise&nbsp;pela Secretaria de Estado de Sa\u00fade.<\/p>\n\n\n\n<p>Maric\u00e1 chegou a 26.880 casos confirmados. A cidade contabiliza 799 \u00f3bitos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Maric\u00e1&nbsp;registrou mais 03 mortes pela Covid-19, segundo a Secretaria Municipal de Sa\u00fade, atrav\u00e9s do boletim epidemiol\u00f3gico divulgado<\/p>\n","protected":false},"author":1,"featured_media":35154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-35152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/35152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=35152"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/35152\/revisions"}],"predecessor-version":[{"id":35155,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/35152\/revisions\/35155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/35154"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=35152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=35152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=35152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}