{"id":36114,"date":"2022-04-09T07:31:04","date_gmt":"2022-04-09T10:31:04","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=36114"},"modified":"2022-04-09T07:31:10","modified_gmt":"2022-04-09T10:31:10","slug":"marica-mais-de-2-600-vitimas-do-temporal-ja-foram-cadastradas-pela-prefeitura","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/04\/09\/marica-mais-de-2-600-vitimas-do-temporal-ja-foram-cadastradas-pela-prefeitura\/","title":{"rendered":"Maric\u00e1: Mais de 2.600 v\u00edtimas do temporal j\u00e1 foram cadastradas pela Prefeitura"},"content":{"rendered":"\n<p>Os cinco polos de atendimento abertos para atender as v\u00edtimas da chuva em Maric\u00e1 cadastraram, at\u00e9 o fim de quinta-feira (07\/04), 2.681 pessoas. Deste total, 906 pessoas procuraram atendimento no polo Mumbuca, justamente um dos bairros mais afetados pela chuva, e outras 867 foram cadastradas no polo Flamengo. No Bananal, foram identificadas at\u00e9 agora 333 v\u00edtimas do temporal, al\u00e9m de 317 no Marqu\u00eas e 250 pessoas em Bambu\u00ed. A sede da Prefeitura em Itaipua\u00e7u, que funciona como centro de coleta de doa\u00e7\u00f5es, acabou cadastrando oito pessoas.<\/p>\n\n\n\n<p>Nos polos, as fam\u00edlias prejudicadas pela forte chuva do fim de semana passado s\u00e3o recebidas por um servi\u00e7o de triagem, que t\u00eam facilitado o acesso aos benef\u00edcios que a Prefeitura de Maric\u00e1 disponibilizou. Ao todo, 91 fam\u00edlias j\u00e1 est\u00e3o com dinheiro do aluguel social na conta do Banco Mumbuca e 60 pessoas desabrigadas foram transferidas para pousadas da cidade com subs\u00eddio do Governo Municipal.<\/p>\n\n\n\n<p>Os polos \u2013 montados no Flamengo, na Mumbuca, no Marqu\u00eas, em Bambu\u00ed e em Itaipua\u00e7u \u2013 contam com equipes multidisciplinares da Defesa Civil e das Secretarias de Habita\u00e7\u00e3o, Direitos Humanos, Assist\u00eancia Social e Economia Solid\u00e1ria, que avaliam as necessidades de cada pessoa e a encaminham para os respectivos servi\u00e7os, como aluguel social e cadastro em programas assistenciais da Prefeitura. Os polos funcionam das 9h \u00e0s 17h, e estar\u00e3o abertos at\u00e9 s\u00e1bado (09\/04).<\/p>\n\n\n\n<p>Al\u00e9m do cadastramento das v\u00edtimas, os polos tamb\u00e9m funcionam como pontos de distribui\u00e7\u00e3o de cestas b\u00e1sicas e de kits com produtos de limpeza: de ter\u00e7a (05) at\u00e9 a quinta-feira (07), foram entregues 2.144 cestas b\u00e1sicas \u2013 771 na Mumbuca, 710 no Flamengo, 284 no Bananal, 230 em Bambu\u00ed, 135 no Marqu\u00eas e sete em Itaipua\u00e7u \u2013 e 2.310 kits de limpeza, dos quais 801 na Mumbuca, 751 no Flamengo, 269 no Bananal, 221 em Bambu\u00ed, 262 no Marqu\u00eas e seis em Itaipua\u00e7u.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os cinco polos de atendimento abertos para atender as v\u00edtimas da chuva em Maric\u00e1 cadastraram, at\u00e9 o fim de quinta-feira<\/p>\n","protected":false},"author":1,"featured_media":36115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-36114","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/36114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=36114"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/36114\/revisions"}],"predecessor-version":[{"id":36116,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/36114\/revisions\/36116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/36115"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=36114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=36114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=36114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}