{"id":38414,"date":"2022-06-10T09:30:42","date_gmt":"2022-06-10T12:30:42","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=38414"},"modified":"2022-06-10T09:30:43","modified_gmt":"2022-06-10T12:30:43","slug":"marica-buracos-na-avenida-roberto-silveira-seguem-causando-transtornos","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/06\/10\/marica-buracos-na-avenida-roberto-silveira-seguem-causando-transtornos\/","title":{"rendered":"Maric\u00e1: Buracos na Avenida Roberto Silveira seguem causando transtornos"},"content":{"rendered":"\n<p>Buracos na Avenida Roberto Silveira, em Maric\u00e1, seguem causando transtornos.<\/p>\n\n\n\n<p>V\u00e1rios trechos da via, que \u00e9 uma das mais movimentadas da cidade, est\u00e1 com v\u00e1rios buracos, causando v\u00e1rios problemas em carros e podendo ocasionar em acidentes.<\/p>\n\n\n\n<p>Os populares pedem uma a\u00e7\u00e3o da autarquia do Servi\u00e7o de Obras de Maric\u00e1 (SOMAR) para efetuar a opera\u00e7\u00e3o tapa-buraco no local.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buracos na Avenida Roberto Silveira, em Maric\u00e1, seguem causando transtornos. V\u00e1rios trechos da via, que \u00e9 uma das mais movimentadas<\/p>\n","protected":false},"author":1,"featured_media":38417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-38414","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=38414"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38414\/revisions"}],"predecessor-version":[{"id":38418,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38414\/revisions\/38418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/38417"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=38414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=38414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=38414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}