{"id":38855,"date":"2022-06-22T14:16:23","date_gmt":"2022-06-22T17:16:23","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=38855"},"modified":"2022-07-14T10:20:10","modified_gmt":"2022-07-14T13:20:10","slug":"marica-policia-civil-investiga-se-traficantes-do-dende-estao-envolvidos-no-desaparecimento-de-motorista-de-aplicativo","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/06\/22\/marica-policia-civil-investiga-se-traficantes-do-dende-estao-envolvidos-no-desaparecimento-de-motorista-de-aplicativo\/","title":{"rendered":"Maric\u00e1: Pol\u00edcia Civil investiga se traficantes do Dend\u00ea est\u00e3o envolvidos no desaparecimento de motorista de aplicativo\u00a0"},"content":{"rendered":"\n<p>A Pol\u00edcia Civil investiga se o traficante Marcos Vin\u00edcius dos Santos, o Chapola, suspeito de comandar o tr\u00e1fico no Morro do Dend\u00ea, na Ilha do Governador, na Zona Norte do Rio, est\u00e1 envolvido no desaparecimento do entregador de supermercados Thiago Gomes dos Santos, de 28 anos. Thiago desapareceu no \u00faltimo domingo, quando trabalhava como motorista de aplicativo.<\/p>\n\n\n\n<p>De acordo com investiga\u00e7\u00f5es preliminares da 17\u00aa DP ( S\u00e3o Crist\u00f3v\u00e3o), o carro dirigido pelo motorista foi visto no Morro do Dend\u00ea pouco depois de o motorista ter transportado um passageiro para as proximidades da comunidade, que tem o com\u00e9rcio de drogas controlado por Chapola. Um dos bandidos mais procurados do Rio, Marcos Vin\u00edcius \u00e9 acusado de integrar uma fac\u00e7\u00e3o criminosa que atua no estado. Ele assumiu o comando do Dend\u00ea, em 2019, depois que o traficante Fernandinho Guarabu, ent\u00e3o chefe do tr\u00e1fico no morro, foi morto em junho daquele ano, em uma troca de tiros com policiais do Batalh\u00e3o de Choque da PM.<\/p>\n\n\n\n<p>Al\u00e9m de Chapola, um bandido conhecido como Neves, que morreu numa troca tiros com policias nesta ter\u00e7a-feira, na Ilha do Governador, tamb\u00e9m estaria envolvido no desaparecimento do motorista de aplicativo. O carro que Thiago dirigia foi encontrado, nesta segunda-feira, com os documentos dele em seu interior, estacionado pr\u00f3ximo \u00e0 feira de tradi\u00e7\u00f5es nordestinas, em S\u00e3o Crist\u00f3v\u00e3o, tamb\u00e9m na Zona Norte do Rio.<\/p>\n\n\n\n<p>A pol\u00edcia tenta descobrir o que teria acontecido com Thiago. Neuseli Gomes da Silva, m\u00e3e do jovem, fez nesta quarta-feira, um apelo para que a pol\u00edcia n\u00e3o pare de fazer buscas pelo filho.<\/p>\n\n\n\n<p>\u2014 Quero meu filho de volta do jeito que ele estiver. A pol\u00edcia tem que continuar procurando para saber o que aconteceu com ele. N\u00e3o durmo direito desde do dia em que meu filho sumiu. Estou a poder de rem\u00e9dios. A \u00faltima vez que ele falou comigo foi no domingo, quando pegou o carro para ir trabalhar. Thiago \u00e9 um menino bom, e n\u00e3o tem inimigos. Ele falava comigo v\u00e1rias vezes ao dia, praticamente me ligava de dez em dez minutos. N\u00e3o iria ficar sem se comunicar tanto tempo caso algo n\u00e3o tivesse acontecido \u2014 disse Neuseli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil investiga se o traficante Marcos Vin\u00edcius dos Santos, o Chapola, suspeito de comandar o tr\u00e1fico no Morro<\/p>\n","protected":false},"author":1,"featured_media":38832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-38855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=38855"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38855\/revisions"}],"predecessor-version":[{"id":38856,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/38855\/revisions\/38856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/38832"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=38855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=38855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=38855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}