{"id":39758,"date":"2022-07-12T08:19:12","date_gmt":"2022-07-12T11:19:12","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=39758"},"modified":"2022-07-14T10:25:36","modified_gmt":"2022-07-14T13:25:36","slug":"motociclista-fica-ferido-apos-cair-no-flamengo","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/07\/12\/motociclista-fica-ferido-apos-cair-no-flamengo\/","title":{"rendered":"Motociclista fica ferido ap\u00f3s cair no Flamengo"},"content":{"rendered":"\n<p>Um motociclista ficou ferido ap\u00f3s cair na Rua Ari Spindola, no Flamengo, em Maric\u00e1, na madrugada desta ter\u00e7a-feira (12).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, o condutor da moto seguia pelo bairro quando perdeu o controle e caiu. Com o impacto, o motociclista sofreu diversos ferimentos pelo corpo.<\/p>\n\n\n\n<p>Bombeiros do Destacamento de Maric\u00e1 foram acionados para o local e prestaram os primeiros socorros para a v\u00edtima, que foi encaminhada para o Hospital Municipal Conde Modesto Leal.<\/p>\n\n\n\n<p>Policiais militares registraram a ocorr\u00eancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um motociclista ficou ferido ap\u00f3s cair na Rua Ari Spindola, no Flamengo, em Maric\u00e1, na madrugada desta ter\u00e7a-feira (12). De<\/p>\n","protected":false},"author":1,"featured_media":38937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-39758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=39758"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39758\/revisions"}],"predecessor-version":[{"id":39759,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39758\/revisions\/39759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/38937"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=39758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=39758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=39758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}