{"id":39998,"date":"2022-07-16T12:11:49","date_gmt":"2022-07-16T15:11:49","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=39998"},"modified":"2022-07-17T18:40:47","modified_gmt":"2022-07-17T21:40:47","slug":"homem-e-flagrado-furtando-tv-de-comercio-no-centro-de-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/07\/16\/homem-e-flagrado-furtando-tv-de-comercio-no-centro-de-marica\/","title":{"rendered":"Homem \u00e9 flagrado furtando TV de com\u00e9rcio no Centro de Maric\u00e1\u00a0"},"content":{"rendered":"\n<p>Um homem furtou uma TV no com\u00e9rcio No Limites Lanches, no Centro de Maric\u00e1, na madrugada desta sexta-feira (15).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, um carro preto parou em frente a loja e um homem pulou o cercado e entrou no estabelecimento.<\/p>\n\n\n\n<p>O criminoso arrombou os dois cadeados que protegiam a TV Samsung 42\u00aa e realizou o furto, fugindo logo em seguida no ve\u00edculo.<\/p>\n\n\n\n<p>C\u00e2meras de seguran\u00e7a de um estacionamento ao lado flagraram toda a a\u00e7\u00e3o criminosa.&nbsp;<\/p>\n\n\n\n<p>O caso foi registrado na 82\u00aa DP (Maric\u00e1).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem furtou uma TV no com\u00e9rcio No Limites Lanches, no Centro de Maric\u00e1, na madrugada desta sexta-feira (15). De<\/p>\n","protected":false},"author":1,"featured_media":40002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-39998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=39998"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39998\/revisions"}],"predecessor-version":[{"id":40000,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/39998\/revisions\/40000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/40002"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=39998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=39998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=39998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}