{"id":40234,"date":"2022-07-21T15:59:03","date_gmt":"2022-07-21T18:59:03","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=40234"},"modified":"2022-07-22T18:38:16","modified_gmt":"2022-07-22T21:38:16","slug":"poste-pega-fogo-no-flamengo-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/07\/21\/poste-pega-fogo-no-flamengo-em-marica\/","title":{"rendered":"Poste pega fogo no Flamengo, em Maric\u00e1"},"content":{"rendered":"\n<p>Um poste de energia pegou fogo, no Flamengo, em Maric\u00e1, na tarde desta quinta-feira (21).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, ap\u00f3s um curto circuito, o poste come\u00e7ou a pegar fogo, se espalhando para os fios.<\/p>\n\n\n\n<p>Bombeiros do Destacamento de Maric\u00e1 foram acionados para o local para combater as chamas.<\/p>\n\n\n\n<p>Equipes de manuten\u00e7\u00e3o da Enel s\u00e3o aguardados na \u00e1rea para realizar o reparo da rede.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um poste de energia pegou fogo, no Flamengo, em Maric\u00e1, na tarde desta quinta-feira (21). De acordo com informa\u00e7\u00f5es, ap\u00f3s<\/p>\n","protected":false},"author":1,"featured_media":40236,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-40234","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=40234"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40234\/revisions"}],"predecessor-version":[{"id":40239,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40234\/revisions\/40239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/40236"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=40234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=40234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=40234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}