{"id":40796,"date":"2022-08-02T08:33:08","date_gmt":"2022-08-02T11:33:08","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=40796"},"modified":"2022-09-09T22:22:43","modified_gmt":"2022-09-10T01:22:43","slug":"defesa-civil-de-marica-informa-que-nao-ha-previsao-de-chuva-para-os-proximos-dias","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/08\/02\/defesa-civil-de-marica-informa-que-nao-ha-previsao-de-chuva-para-os-proximos-dias\/","title":{"rendered":"Defesa Civil de Maric\u00e1 informa que n\u00e3o h\u00e1 previs\u00e3o de chuva para os pr\u00f3ximos dias\u00a0"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Prote\u00e7\u00e3o e Defesa Civil, informa que n\u00e3o h\u00e1 previs\u00e3o de chuva para os pr\u00f3ximos dias devido \u00e0 influ\u00eancia de um sistema de alta press\u00e3o no munic\u00edpio.<\/p>\n\n\n\n<p>Nesta segunda-feira (01\/08) e ter\u00e7a-feira (02\/08) o c\u00e9u se manter\u00e1 claro e com poucas nuvens, sem previs\u00e3o de chuva. Os ventos ter\u00e3o intensidade fraca a moderada, temperatura m\u00ednima de 18\u00b0C e m\u00e1xima de 30\u00b0C. A umidade relativa do ar variar\u00e1 entre 40% e 90%.<\/p>\n\n\n\n<p>Na quarta-feira (03\/08), o c\u00e9u se mant\u00e9m claro e com poucas nuvens, sem previs\u00e3o de chuva. Os ventos permanecem com intensidade fraca a moderada. A temperatura m\u00ednima ser\u00e1 de 17\u00b0C e a m\u00e1xima de 28\u00b0C. A umidade relativa do ar mant\u00e9m a varia\u00e7\u00e3o entre 40% e 90%.<\/p>\n\n\n\n<p>As equipes da Defesa Civil permanecem de prontid\u00e3o 24 horas no centro operacional e podem ser acionadas pelos telefones 199,&nbsp;<a href=\"tel:2637-1999\">2637-1999<\/a>&nbsp;ou pelo WhatsApp&nbsp;<a href=\"tel:(21) 97000-5782\">(21) 97000-5782<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Prote\u00e7\u00e3o e Defesa Civil, informa que n\u00e3o h\u00e1 previs\u00e3o de chuva<\/p>\n","protected":false},"author":1,"featured_media":40798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-40796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=40796"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40796\/revisions"}],"predecessor-version":[{"id":40799,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/40796\/revisions\/40799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/40798"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=40796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=40796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=40796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}