{"id":41445,"date":"2022-08-15T10:40:42","date_gmt":"2022-08-15T13:40:42","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=41445"},"modified":"2022-09-09T22:42:59","modified_gmt":"2022-09-10T01:42:59","slug":"jovem-e-baleado-e-homem-preso-apos-troca-de-tiros-com-a-pm-no-risca-faca-em-inoa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/08\/15\/jovem-e-baleado-e-homem-preso-apos-troca-de-tiros-com-a-pm-no-risca-faca-em-inoa\/","title":{"rendered":"Jovem \u00e9 baleado e homem preso ap\u00f3s troca de tiros com a PM no Risca Faca, em Ino\u00e3"},"content":{"rendered":"\n<p>Um jovem ficou ferido e um homem foi preso ap\u00f3s uma troca de tiros com a PM, no Risca Faca, em Ino\u00e3, na manh\u00e3 desta segunda-feira (15).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, policiais seguiam em uma patrulhamento pelo bairro quando foram alvo de criminosos. Os militares revidaram e houve uma troca de tiros.<\/p>\n\n\n\n<p>Ap\u00f3s o confronto, um adolescente foi baleado e outro preso. O acusado foi socorrido para o Hospital Municipal Conde Modesto Leal, em Maric\u00e1, e em seguida, encaminhado para o Hospital Estadual Alberto Torres, em S\u00e3o Gon\u00e7alo.<\/p>\n\n\n\n<p>Na a\u00e7\u00e3o, foram apreendidas drogas e uma arma. O preso foi encaminhado para a 82\u00aa DP (Maric\u00e1), onde o caso foi registrado.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um jovem ficou ferido e um homem foi preso ap\u00f3s uma troca de tiros com a PM, no Risca Faca,<\/p>\n","protected":false},"author":1,"featured_media":41447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-41445","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=41445"}],"version-history":[{"count":3,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41445\/revisions"}],"predecessor-version":[{"id":41451,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41445\/revisions\/41451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/41447"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=41445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=41445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=41445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}