{"id":41803,"date":"2022-08-20T19:22:38","date_gmt":"2022-08-20T22:22:38","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=41803"},"modified":"2022-09-09T22:49:34","modified_gmt":"2022-09-10T01:49:34","slug":"dupla-e-presa-pela-pm-em-niteroi-apos-furtar-moto-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/08\/20\/dupla-e-presa-pela-pm-em-niteroi-apos-furtar-moto-em-itaipuacu\/","title":{"rendered":"Dupla \u00e9 presa pela PM em Niter\u00f3i ap\u00f3s furtar moto em Itaipua\u00e7u&nbsp;"},"content":{"rendered":"\n<p>Policiais militares prenderam dois homens em Niter\u00f3i, acusados de furtar uma moto no Recanto, em Itaipua\u00e7u, na noite deste s\u00e1bado (20).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, policiais patrulhavam quando avistaram a dupla em atitude suspeita. Os homens foram abordados e reconhecidos como os autores do crime na cidade de Maric\u00e1.<\/p>\n\n\n\n<p>A moto furtada em Itaipua\u00e7u n\u00e3o foi encontrada com os criminosos, que n\u00e3o deram informa\u00e7\u00f5es sobre o ve\u00edculo.&nbsp;<\/p>\n\n\n\n<p>Os homens foram conduzidos para a Central de Flagrantes da Pol\u00edcia Civil, 76\u00aa DP, em Niter\u00f3i.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares prenderam dois homens em Niter\u00f3i, acusados de furtar uma moto no Recanto, em Itaipua\u00e7u, na noite deste s\u00e1bado<\/p>\n","protected":false},"author":1,"featured_media":41806,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-41803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=41803"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41803\/revisions"}],"predecessor-version":[{"id":41807,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/41803\/revisions\/41807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/41806"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=41803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=41803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=41803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}