{"id":42752,"date":"2022-09-16T08:07:53","date_gmt":"2022-09-16T11:07:53","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=42752"},"modified":"2022-09-19T08:27:17","modified_gmt":"2022-09-19T11:27:17","slug":"ator-jose-dumont-e-preso-por-armazenar-pornografia-infantil","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/09\/16\/ator-jose-dumont-e-preso-por-armazenar-pornografia-infantil\/","title":{"rendered":"Ator Jos\u00e9 Dumont \u00e9 preso por armazenar pornografia infantil\u00a0"},"content":{"rendered":"\n<p>O ator&nbsp;Jos\u00e9 Dumont foi preso em flagrante nesta quinta-feira (15) suspeito de armazenar imagens de pornografia infantil&nbsp;no celular e no computador pessoal. Ele est\u00e1 sendo&nbsp;investigado tamb\u00e9m por supostamente ter cometido abusos contra um menino de 12 anos.<\/p>\n\n\n\n<p>A den\u00fancia partiu de vizinhos. Segundo a investiga\u00e7\u00e3o, c\u00e2meras de seguran\u00e7a do condom\u00ednio onde ele mora flagraram o ator cometendo abusos contra um\u00a0adolescente de 12 anos, como\u00a0beijos e car\u00edcias.<\/p>\n\n\n\n<p>A pol\u00edcia informou que ele se aproximou do menino h\u00e1 um ano, ao oferecer ajuda financeira e presentes.<\/p>\n\n\n\n<p>Nesta quinta, ao cumprir o mandado de busca e apreens\u00e3o na casa do ator, os policiais encontraram\u00a0v\u00eddeos e fotos contendo pornografia infantil no celular pessoal e no computador. A Justi\u00e7a tamb\u00e9m tinha autorizado a quebra de sigilo de dados.<\/p>\n\n\n\n<p>Jos\u00e9 Dumont foi preso em flagrante. De acordo com o Estatuto da Crian\u00e7a e do Adolescente, armazenar imagens de sexo envolvendo crian\u00e7as \u00e9 crime.&nbsp;<\/p>\n\n\n\n<p>O ator foi levado para Delegacia da Crian\u00e7a e do Adolescente V\u00edtima (Dcav).&nbsp;<\/p>\n\n\n\n<p>No fim da tarde, Jos\u00e9&nbsp;passou por uma audi\u00eancia de cust\u00f3dia e teve a pris\u00e3o mantida.<\/p>\n\n\n\n<p>A defesa de Jos\u00e9 Dumont n\u00e3o se pronunciou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ator&nbsp;Jos\u00e9 Dumont foi preso em flagrante nesta quinta-feira (15) suspeito de armazenar imagens de pornografia infantil&nbsp;no celular e no<\/p>\n","protected":false},"author":1,"featured_media":42755,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-42752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/42752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=42752"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/42752\/revisions"}],"predecessor-version":[{"id":42759,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/42752\/revisions\/42759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/42755"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=42752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=42752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=42752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}