{"id":43009,"date":"2022-09-21T08:56:25","date_gmt":"2022-09-21T11:56:25","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=43009"},"modified":"2022-10-06T12:02:39","modified_gmt":"2022-10-06T15:02:39","slug":"travessia-espraiado-tomascar-e-o-proximo-destino-do-circuito-ecologico-deste-sabado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/09\/21\/travessia-espraiado-tomascar-e-o-proximo-destino-do-circuito-ecologico-deste-sabado\/","title":{"rendered":"Travessia Espraiado-Tomascar \u00e9 o pr\u00f3ximo destino do Circuito Ecol\u00f3gico deste s\u00e1bado\u00a0"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Turismo, realiza no pr\u00f3ximo s\u00e1bado (24\/09) mais uma etapa do Circuito Ecol\u00f3gico Caminhos de Maric\u00e1 com a travessia entre os bairros do Espraiado e Tomascar, este no munic\u00edpio de Tangu\u00e1. Com in\u00edcio a partir das 8h30, trajeto \u00e9 considerado pesado, com trechos de subida \u00edngreme, e tem dura\u00e7\u00e3o aproximada de seis horas entre a ida e a volta. As inscri\u00e7\u00f5es come\u00e7am nesta quinta-feira (22\/09), a partir de 13h, por meio do link (https:\/\/forms.gle\/kEmY5ujGsMMAwxGB8).<\/p>\n\n\n\n<p>O percurso come\u00e7a com subida pelo Vale de S\u00e3o Francisco at\u00e9 o cume, no Espraiado e, em seguida, os participantes descem at\u00e9 Tomascar. O vilarejo foi uma antiga fazenda, onde ainda existe um moinho de farinha de roda d\u2019\u00e1gua constru\u00eddo no s\u00e9culo XIX com c\u00f3rregos e cachoeiras no trajeto. Com objetivo de estimular o com\u00e9rcio local no entorno das \u00e1reas naturais protegidas, os participantes contar\u00e3o com almo\u00e7o opcional no restaurante da Marilene ao custo m\u00e9dio de R$ 25.<\/p>\n\n\n\n<p>O ponto de encontro ser\u00e1 na Cachoeira do Espraiado, que fica a cerca de um quil\u00f4metro ap\u00f3s o ponto final da linha E-06 (Centro x Espraiado), \u00f4nibus tarifa zero da Empresa P\u00fablica de Transportes (EPT), que sai da Rodovi\u00e1ria do Povo com intervalo de 40 minutos. A recomenda\u00e7\u00e3o aos participantes \u00e9 levar itens como repelente, ao menos dois litros de \u00e1gua, toalha ou canga, lanche, protetor solar, uma muda de roupa extra e medicamentos de uso pessoal, al\u00e9m de vestir roupas leves, bon\u00e9 e cal\u00e7ado com travas.<\/p>\n\n\n\n<p>Mais informa\u00e7\u00f5es podem ser obtidas na Secretaria de Turismo de Maric\u00e1 (Pra\u00e7a Conselheiro Macedo Soares, s\/n\u00ba \u2013 Centro) ou pelo telefone&nbsp;<a href=\"tel:(21) 97107-8991\">(21) 97107-8991<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Turismo, realiza no pr\u00f3ximo s\u00e1bado (24\/09) mais uma etapa do Circuito<\/p>\n","protected":false},"author":1,"featured_media":43011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[],"class_list":["post-43009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esporte"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=43009"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43009\/revisions"}],"predecessor-version":[{"id":43012,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43009\/revisions\/43012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/43011"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=43009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=43009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=43009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}