{"id":43683,"date":"2022-10-06T08:37:07","date_gmt":"2022-10-06T11:37:07","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=43683"},"modified":"2022-10-06T12:18:02","modified_gmt":"2022-10-06T15:18:02","slug":"cultura-abre-inscricoes-para-workshop-sobre-tecnicas-e-conservacao-de-obras-de-arte","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/10\/06\/cultura-abre-inscricoes-para-workshop-sobre-tecnicas-e-conservacao-de-obras-de-arte\/","title":{"rendered":"Cultura abre inscri\u00e7\u00f5es para workshop sobre t\u00e9cnicas e conserva\u00e7\u00e3o de obras de arte\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Prefeitura de Maric\u00e1, por meio da Secretaria de Cultura, est\u00e1 com inscri\u00e7\u00f5es abertas, at\u00e9 sexta-feira (07\/10), com 25 vagas para o workshop \u201cT\u00e9cnicas e Conserva\u00e7\u00e3o de Obras de Arte\u201d, que acontece nos dias 10 e 17 de outubro, a partir das 19h, na sala de palestras da Secretaria de Desenvolvimento Econ\u00f4mico, que fica na Rua Dom\u00edcio da Gama, 259, no Centro de Maric\u00e1, em frente ao Cine Teatro Municipal Henfil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A a\u00e7\u00e3o tem o objetivo de elucidar d\u00favidas de artistas iniciantes sobre materiais e t\u00e9cnicas historicamente utilizadas, trazer conhecimento para moradores da cidade no campo das artes e criar parcerias entre profissionais da \u00e1rea no munic\u00edpio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA capacita\u00e7\u00e3o profissional \u00e9 um instrumento fundamental na constru\u00e7\u00e3o da consci\u00eancia coletiva. Por isso a gente trouxe esse treinamento t\u00e3o importante e espec\u00edfico para os artistas da nossa cidade\u201d, destacou o secret\u00e1rio de Cultura, Sady Bianchin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A primeira aula, no dia 10, ser\u00e1 sobre pintura, policromias, diversidade de suporte, arte contempor\u00e2nea e seus desafios com J\u00e9ssica da Matta, coordenadora de Patrim\u00f4nio Hist\u00f3rico e Cultural de Maric\u00e1, e Aline Vecchi, muse\u00f3loga do munic\u00edpio de Araruama. J\u00e1 a segunda ministra\u00e7\u00e3o, no dia 17, vai falar sobre craquelamento, biodeterioriza\u00e7\u00e3o e agentes de deteriora\u00e7\u00e3o com J\u00e9ssica da Matta. Os interessados podem se inscrever pelo link&nbsp;<a href=\"https:\/\/tinyurl.com\/workshopobrasdearte\">https:\/\/tinyurl.com\/workshopobrasdearte<\/a>at\u00e9 12h desta sexta-feira (07\/10).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Cultura, est\u00e1 com inscri\u00e7\u00f5es abertas, at\u00e9 sexta-feira (07\/10), com 25 vagas<\/p>\n","protected":false},"author":1,"featured_media":43684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-43683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=43683"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43683\/revisions"}],"predecessor-version":[{"id":43685,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/43683\/revisions\/43685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/43684"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=43683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=43683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=43683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}