{"id":44449,"date":"2022-10-23T12:04:54","date_gmt":"2022-10-23T15:04:54","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=44449"},"modified":"2022-10-23T12:04:54","modified_gmt":"2022-10-23T15:04:54","slug":"acao-social-leva-diversos-servicos-da-prefeitura-para-a-populacao-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/10\/23\/acao-social-leva-diversos-servicos-da-prefeitura-para-a-populacao-em-itaipuacu\/","title":{"rendered":"A\u00e7\u00e3o social leva diversos servi\u00e7os da Prefeitura para a popula\u00e7\u00e3o em Itaipua\u00e7u"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Assist\u00eancia Social, realizou no s\u00e1bado (22\/10) uma a\u00e7\u00e3o que levou diversos servi\u00e7os municipais para a popula\u00e7\u00e3o, na Escola Municipal Oswaldo Lima Rodrigues, em Itaipua\u00e7u.<\/p>\n\n\n\n<p>Durante a a\u00e7\u00e3o social, foram feitos 30 agendamentos para emiss\u00e3o de carteira de identidade, 18 solicita\u00e7\u00f5es de 2\u00aa via de certid\u00e3o de nascimento, 30 inscri\u00e7\u00f5es no Cad\u00danico e aproximadamente 100 informa\u00e7\u00f5es pontuais sobre servi\u00e7os oferecidos pela Prefeitura.<\/p>\n\n\n\n<p>Quem passou pelo local tamb\u00e9m p\u00f4de agendar a segunda via de documentos e tributos com a equipe do Servi\u00e7os Integrados Municipal (SIM), solicitar a segunda via das certid\u00f5es de casamento ou \u00f3bito, declara\u00e7\u00e3o de hipossufici\u00eancia para o Detran, entre outros servi\u00e7os gratuitos.<\/p>\n\n\n\n<p>Al\u00e9m disso, foram oferecidos servi\u00e7os de Sa\u00fade Bucal (aplica\u00e7\u00e3o de fl\u00faor e correta escova\u00e7\u00e3o), aferi\u00e7\u00e3o de press\u00e3o arterial, oficinas de manicure, corte de cabelo e maquiagem, orienta\u00e7\u00f5es do Centro de Refer\u00eancia Especializado da Assist\u00eancia Social (Creas), do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos, consultas sobre o benef\u00edcio Aux\u00edlio Brasil, Acolhimento Social (documenta\u00e7\u00e3o) e Assessoria Jur\u00eddica.<\/p>\n\n\n\n<p>O evento contou ainda com palestras sobre preven\u00e7\u00e3o ao c\u00e2ncer de mama (Outubro Rosa), informa\u00e7\u00f5es sobre a carteira do idoso (Passe Interestadual), capta\u00e7\u00e3o de curr\u00edculo para banco de dados da Prefeitura, al\u00e9m de atividades como apresenta\u00e7\u00e3o de dan\u00e7a cigana e distribui\u00e7\u00e3o de mudas e alimentos desidratados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Assist\u00eancia Social, realizou no s\u00e1bado (22\/10) uma a\u00e7\u00e3o que levou diversos<\/p>\n","protected":false},"author":1,"featured_media":44451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-44449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=44449"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44449\/revisions"}],"predecessor-version":[{"id":44452,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44449\/revisions\/44452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/44451"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=44449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=44449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=44449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}