{"id":44464,"date":"2022-10-24T08:57:42","date_gmt":"2022-10-24T11:57:42","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=44464"},"modified":"2022-10-24T08:57:43","modified_gmt":"2022-10-24T11:57:43","slug":"saude-abre-a-exposicao-que-incentiva-a-prevencao-ao-cancer-de-mama-no-shopping-boulevard","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/10\/24\/saude-abre-a-exposicao-que-incentiva-a-prevencao-ao-cancer-de-mama-no-shopping-boulevard\/","title":{"rendered":"Sa\u00fade abre a exposi\u00e7\u00e3o que incentiva a preven\u00e7\u00e3o ao c\u00e2ncer de mama no Shopping Boulevard"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Sa\u00fade, abriu na quinta-feira (20\/10) a exposi\u00e7\u00e3o \u201cTem marcas que o tempo pode evitar\u201d, que apresenta pain\u00e9is com depoimentos de mulheres que enfrentaram e venceram o c\u00e2ncer de mama, uma maneira de estimular a preven\u00e7\u00e3o e o diagn\u00f3stico precoce da doen\u00e7a \u2014 que possui mais de 90% de chances de cura quando descoberta nos est\u00e1gios iniciais. A mostra gratuita faz parte das a\u00e7\u00f5es voltadas ao Outubro Rosa e ocorre at\u00e9 o dia 30\/10 no hall de entrada do shopping Boulevard Maric\u00e1, no Centro.<\/p>\n\n\n\n<p>A abertura da atividade contou com m\u00fasica ao vivo e homenagens \u00e0s moradoras expostas nos pain\u00e9is, que receberam flores dos gestores da sa\u00fade do munic\u00edpio e tamb\u00e9m compartilharam as suas viv\u00eancias \u00e0 popula\u00e7\u00e3o presente. Dessa forma, elas proporcionaram um momento de conscientiza\u00e7\u00e3o e inspira\u00e7\u00e3o a outras pessoas que passam por situa\u00e7\u00f5es similares, refor\u00e7ando que o c\u00e2ncer de mama tem cura, al\u00e9m de lembrar que o exame preventivo e a mamografia s\u00e3o procedimentos fundamentais para o rastreio e iniciar o tratamento o quanto antes.<\/p>\n\n\n\n<p>Luana Rodrigues, subsecret\u00e1ria da Rede de Aten\u00e7\u00e3o \u00e0 Sa\u00fade, ressaltou o impacto dos depoimentos, essenciais para um olhar mais atento aos sinais e ampliar o entendimento sobre as medidas de preven\u00e7\u00e3o entre os maricaenses.<\/p>\n\n\n\n<p>\u201cA exposi\u00e7\u00e3o das mulheres que venceram o c\u00e2ncer de mama \u00e9 muito importante para o munic\u00edpio, porque elas trazem a sua experi\u00eancia de supera\u00e7\u00e3o e refor\u00e7am o papel do diagn\u00f3stico precoce para salvar vidas. O c\u00e2ncer de mama tem cura e devemos v\u00ea-lo como algo a ser enfrentado e vencido. Por isso, convidamos a popula\u00e7\u00e3o para visitar a exposi\u00e7\u00e3o, conhecendo hist\u00f3rias que servem de exemplo para que outras mulheres se previnam e as que enfrentam a doen\u00e7a tenham mais for\u00e7as para superar\u201d, afirmou.<\/p>\n\n\n\n<p><strong>Popula\u00e7\u00e3o movimenta a exposi\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p>Dezenas de pessoas participaram da abertura da exposi\u00e7\u00e3o, tendo contato com hist\u00f3rias inspiradoras e ampliando a conscientiza\u00e7\u00e3o sobre o tema. Uma das homenageadas presentes foi Ana Maria da Silva, de 62 anos, moradora de Santa Paula. Ela lembrou que teve o diagn\u00f3stico do c\u00e2ncer de mama j\u00e1 em um quadro com complica\u00e7\u00f5es e garantiu que a preven\u00e7\u00e3o \u00e9 o melhor caminho para a cura.<\/p>\n\n\n\n<p>\u201cSer representada na exposi\u00e7\u00e3o \u00e9 um privil\u00e9gio e sou um exemplo de supera\u00e7\u00e3o. Descobri o c\u00e2ncer de mama h\u00e1 10 anos, j\u00e1 em est\u00e1gio avan\u00e7ado, ent\u00e3o \u00e9 uma felicidade compartilhar a minha hist\u00f3ria e fazer com que as mulheres n\u00e3o desanimem, correndo atr\u00e1s da sua vit\u00f3ria. Quando o diagn\u00f3stico \u00e9 precoce, o tratamento tem mais chances de cura e \u00e9 menos doloroso, por isso pe\u00e7o que todas se conscientizem e fa\u00e7am os exames\u201d, pontuou Ana Maria.<\/p>\n\n\n\n<p>Kamila Santos de Souza, de 31 anos, \u00e9 moradora do bairro Pindobas e aprovou os pain\u00e9is expostos, lembrando o impacto das viv\u00eancias dessas mulheres para que outras estejam mais atentas \u00e0 sua sa\u00fade.<\/p>\n\n\n\n<p>\u201cA exposi\u00e7\u00e3o est\u00e1 maravilhosa e podermos acompanhar tudo que elas viveram \u00e9 inspirador, representando a luta e a vit\u00f3ria contra o c\u00e2ncer de mama. Isso \u00e9 um incentivo para realizarmos os exames preventivos, porque muitas vezes vamos deixando o tempo passar, n\u00e3o nos atentamos, mas precisamos respeitar a nossa sa\u00fade. Falar sobre o c\u00e2ncer de mama \u00e9 um ato de cuidado e tenho certeza que essa atividade ir\u00e1 conscientizar muitas mulheres\u201d, concluiu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Sa\u00fade, abriu na quinta-feira (20\/10) a exposi\u00e7\u00e3o \u201cTem marcas que o<\/p>\n","protected":false},"author":1,"featured_media":44466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-44464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=44464"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44464\/revisions"}],"predecessor-version":[{"id":44467,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/44464\/revisions\/44467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/44466"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=44464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=44464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=44464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}