{"id":45155,"date":"2022-11-09T14:21:22","date_gmt":"2022-11-09T17:21:22","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=45155"},"modified":"2022-11-17T22:37:57","modified_gmt":"2022-11-18T01:37:57","slug":"policia-ambiental-apreende-13-passaros-silvestres-no-manu-manuela","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/11\/09\/policia-ambiental-apreende-13-passaros-silvestres-no-manu-manuela\/","title":{"rendered":"Pol\u00edcia Ambiental apreende 13 p\u00e1ssaros silvestres\u00a0no Manu Manuela"},"content":{"rendered":"\n<p>Policiais militares da Unidade de Pol\u00edcia Ambiental (Upam) apreenderam 13 p\u00e1ssaros silvestres, no Manu Manuela, na manh\u00e3 desta quarta-feira (09).<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es, ap\u00f3s den\u00fancias an\u00f4nimas, militares seguiram at\u00e9 a resid\u00eancia e encontraram encontraram 8 tizius, 3 coleiros, 1 sanha\u00e7u e 1 trinca ferro em cativeiro. <\/p>\n\n\n\n<p>O propriet\u00e1rio n\u00e3o apresentou as licen\u00e7as legais e os animais foram aprendidos.\u00a0<\/p>\n\n\n\n<p>Os animais foram encaminhados para a 82\u00aa DP (Maric\u00e1), onde o caso foi registrado.&nbsp;<\/p>\n\n\n\n<p>Os p\u00e1ssaros ser\u00e3o encaminhados para o Centro de Triagem de Animais Silvestres (Cetas), em Serep\u00f3dica, no Rio de Janeiro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Policiais militares da Unidade de Pol\u00edcia Ambiental (Upam) apreenderam 13 p\u00e1ssaros silvestres, no Manu Manuela, na manh\u00e3 desta quarta-feira (09).<\/p>\n","protected":false},"author":1,"featured_media":45157,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-45155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/45155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=45155"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/45155\/revisions"}],"predecessor-version":[{"id":45160,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/45155\/revisions\/45160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/45157"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=45155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=45155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=45155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}