{"id":47133,"date":"2022-12-28T08:50:48","date_gmt":"2022-12-28T11:50:48","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=47133"},"modified":"2023-01-04T01:06:30","modified_gmt":"2023-01-04T04:06:30","slug":"prefeito-fabiano-horta-recebe-comitiva-da-universidade-iguacu-unig","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2022\/12\/28\/prefeito-fabiano-horta-recebe-comitiva-da-universidade-iguacu-unig\/","title":{"rendered":"Prefeito Fabiano Horta recebe comitiva da Universidade Igua\u00e7u (UNIG)"},"content":{"rendered":"\n<p>O prefeito Fabiano Horta recebeu nesta ter\u00e7a-feira (27\/12) uma comitiva da Universidade Igua\u00e7u (UNIG) para discutir tratativas de implanta\u00e7\u00e3o do polo universit\u00e1rio em Maric\u00e1. A reuni\u00e3o aconteceu no gabinete do prefeito e teve a participa\u00e7\u00e3o da secret\u00e1ria de Educa\u00e7\u00e3o, Adriana Costa, do subsecret\u00e1rio de Desenvolvimento Econ\u00f4mico, Magnun Amado, e demais representantes do governo.<\/p>\n\n\n\n<p>A secret\u00e1ria de Educa\u00e7\u00e3o, Adriana Costa, explicou que a instala\u00e7\u00e3o da universidade est\u00e1 vinculada ao credenciamento ao Programa Passaporte Universit\u00e1rio, que j\u00e1 possui cinco institui\u00e7\u00f5es privadas: Est\u00e1cio de S\u00e1, UniLasalle, Faculdade Cenecista, Centro Universit\u00e1rio Serra dos \u00d3rg\u00e3os (Unifeso) e Universidade de Vassouras, que tem dois polos funcionando no bairro Flamengo.<\/p>\n\n\n\n<p>\u201cIsso \u00e9 motivo de orgulho e mostra que o Programa Passaporte Universit\u00e1rio est\u00e1 sendo referencial para o nosso munic\u00edpio. O que queremos \u00e9 isso, que a universidade venha para c\u00e1, que a popula\u00e7\u00e3o possa estudar e trabalhar na nossa cidade\u201d, afirmou a secret\u00e1ria.<\/p>\n\n\n\n<p>Representante da UNIG, Vin\u00edcius Ramires est\u00e1 confiante que a universidade possa se instalar na cidade e oferecer novas oportunidades de estudo para a popula\u00e7\u00e3o. \u201cDentro de um plano de expans\u00e3o, encontramos em Maric\u00e1 possibilidades de desenvolver o ensino e esse encontro com o prefeito Fabiano Horta veio referendar os nossos anseios. \u00c9 trazer mais uma op\u00e7\u00e3o de ensino superior em todos os seus \u00e2mbitos de gradua\u00e7\u00e3o, p\u00f3s-gradua\u00e7\u00e3o e Ensino \u00e0 Dist\u00e2ncia (EAD) e assim gerar emprego, trabalho, conhecimento cient\u00edfico e t\u00e9cnico para o munic\u00edpio\u201d, disse Vin\u00edcius, que tem a expectativa de oferecer cursos de Medicina, Veterin\u00e1ria, Turismo, entre outros.<\/p>\n\n\n\n<p>A UNIG tem 54 anos de exist\u00eancia e possui campus em Itaperuna e Nova Igua\u00e7u. Ao todo, a universidade oferece 19 cursos, como Direito, Fisioterapia e Enfermagem e demais cursos aos cerca de 15 mil alunos matriculados de forma presencial, al\u00e9m dos que estudam online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Fabiano Horta recebeu nesta ter\u00e7a-feira (27\/12) uma comitiva da Universidade Igua\u00e7u (UNIG) para discutir tratativas de implanta\u00e7\u00e3o do<\/p>\n","protected":false},"author":1,"featured_media":47135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-47133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=47133"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47133\/revisions"}],"predecessor-version":[{"id":47136,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47133\/revisions\/47136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/47135"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=47133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=47133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=47133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}