{"id":47458,"date":"2023-01-05T12:15:12","date_gmt":"2023-01-05T15:15:12","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=47458"},"modified":"2023-01-05T12:15:13","modified_gmt":"2023-01-05T15:15:13","slug":"mc-donalds-e-autuado-por-armazenamento-irregular-em-sao-jose-do-imbassai","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/01\/05\/mc-donalds-e-autuado-por-armazenamento-irregular-em-sao-jose-do-imbassai\/","title":{"rendered":"MC DONALD\u2019S \u00c9 AUTUADO POR ARMAZENAMENTO IRREGULAR EM S\u00c3O JOS\u00c9 DO IMBASSA\u00cd"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, atrav\u00e9s da Secretaria de Defesa do Consumidor, autuou o MC Donald\u2019s por armazenamento irregular, em S\u00e3o Jos\u00e9 do Imbassa\u00ed, nesta quarta -feira (04)<\/p>\n\n\n\n<p>No decorrer do dia de ontem, os fiscais estiveram nas ruas apurando poss\u00edveis irregularidades denunciadas pelos consumidores<\/p>\n\n\n\n<p>No Mc Donald\u2019s, em S\u00e3o Jos\u00e9, os fiscais descartaram 7,5L de milkshake armazenado de forma incorreta, a rede de fast-food foi autuada<\/p>\n\n\n\n<p>No mercado do Gomes, no bairro de Ponta Negra, NENHUMA IRREGULARIDADE foi encontrada e o mercado se adequou as exig\u00eancias feitas quanto a higiene, a estrutura e armazenamento dos alimentos<\/p>\n\n\n\n<p>No hortifruti Cordeirinho, no bairro de Cordeirinho, NENHUMA IRREGULARIDADE foi encontrada.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, atrav\u00e9s da Secretaria de Defesa do Consumidor, autuou o MC Donald\u2019s por armazenamento irregular, em S\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":47460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-47458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=47458"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47458\/revisions"}],"predecessor-version":[{"id":47461,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/47458\/revisions\/47461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/47460"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=47458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=47458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=47458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}