{"id":48115,"date":"2023-01-29T19:19:44","date_gmt":"2023-01-29T22:19:44","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=48115"},"modified":"2023-01-31T20:18:42","modified_gmt":"2023-01-31T23:18:42","slug":"marica-comemora-dia-da-visibilidade-trans","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/01\/29\/marica-comemora-dia-da-visibilidade-trans\/","title":{"rendered":"Maric\u00e1 comemora Dia da Visibilidade Trans"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Participa\u00e7\u00e3o Popular, Direitos Humanos e Mulher, realizou neste domingo (29\/01), na Pra\u00e7a Orlando de Barros Pimentel (Centro), um ato pol\u00edtico cultural em comemora\u00e7\u00e3o ao Dia da Visibilidade Trans. O evento teve o objetivo de destacar a garantia da prote\u00e7\u00e3o social para a popula\u00e7\u00e3o transexual e travesti, assim como acontece em v\u00e1rios lugares do Brasil nesta data, e faz parte do cronograma de atividades do munic\u00edpio voltadas para este p\u00fablico.<\/p>\n\n\n\n<p>Durante o ato, homenagens foram prestadas \u00e0 travesti Marcia Shokena, assassinada em 2020 no Boqueir\u00e3o, e \u00e0 Safira de Martinelli, pai de santo que faleceu em 2021, v\u00edtima da Covid-19.<br>\u201cA gente vem aqui hoje, em pleno domingo, para que todo mundo escute que \u00e9 muito importante lutar pelo reconhecimento e visibilidade das vidas da popula\u00e7\u00e3o trans. Vidas trans importam. A gente precisa de pol\u00edticas p\u00fablicas e que a popula\u00e7\u00e3o entenda que, muitas vezes, n\u00f3s n\u00e3o temos as mesmas oportunidades que as outras pessoas. Por isso, levantamos nossas vozes a favor dessa luta\u201d, afirmou a coordenadora da pasta LGBTQIA+ e do Movimento Popular da Juventude (MPJ), Allie Monteiro.<\/p>\n\n\n\n<p>Filme sobre Indianara \u00e9 exibido no Cine Henfil<\/p>\n\n\n\n<p>Na noite de sexta-feira (27\/01), moradores e convidados estiveram no Cine Henfil (Centro), prestigiando a exibi\u00e7\u00e3o do longa-metragem \u201cIndianara\u201d. Dirigido pela francesa Aude Chevalier-Beaumel e pelo brasileiro Marcelo Barbosa, o filme diz respeito \u00e0 ativista trans que ficou conhecida pelo trabalho de acolhimento a pessoas LGBTQIA+ na casa NEM, no Rio de Janeiro, com direito a comida, educa\u00e7\u00e3o e orienta\u00e7\u00e3o.<\/p>\n\n\n\n<p>O document\u00e1rio mostra como Indianarae Siqueira lidera um grupo de mulheres transg\u00eanero que lutam pela pr\u00f3pria sobreviv\u00eancia em um lugar tomado por preconceito, intoler\u00e2ncia e polariza\u00e7\u00e3o. Desde disputas partid\u00e1rias at\u00e9 o puro combate contra o governo opressor, a ativista de origens humildes passou por uma longa trajet\u00f3ria at\u00e9 se tornar \u00edcone do movimento.<\/p>\n\n\n\n<p>\u201cIndianarae \u00e9 uma refer\u00eancia no Brasil na defesa das pessoas trans e travestis e de toda a comunidade LGBTQIA+. Ela representa todo esse espa\u00e7o de combate pela cidadania, pelo respeito a orienta\u00e7\u00e3o sexual. Uma pessoa que luta por todas as causas da justi\u00e7a social e de g\u00eanero, contra o machismo e todas as formas de preconceito\u201d, explica o coordenador municipal LGBTQIA+ de Maric\u00e1 e do F\u00f3rum LGBTQIA+, Carlos Alves.<\/p>\n\n\n\n<p>Ativistas falam sobre as mudan\u00e7as para travestis<\/p>\n\n\n\n<p>Ativista do movimento LGBTQIA+ h\u00e1 30 anos, Katya Jones, de 73 anos, viveu a \u00e9poca de chumbo da ditadura militar entre os anos 60 e 70 e disse o que mudou para os travestis daquele per\u00edodo para os dias atuais. \u201cA gente n\u00e3o tinha emprego, s\u00f3 podia sair \u00e0 noite e se fosse pego na rua ficava preso por tr\u00eas meses. Com o tempo fomos nos unindo, vendo os movimentos em outros pa\u00edses, come\u00e7aram a aparecer gays em fam\u00edlias tradicionais e hoje podemos andar na rua, alterar os nomes e fazer cirurgia de troca de sexo\u201d, afirmou.<\/p>\n\n\n\n<p>Katya Jones \u00e9 natural do Rio de Janeiro, mora em Ino\u00e3 h\u00e1 15 anos e destacou que a luta pelos direitos de travestis avan\u00e7ou, mas ainda tem muito a conquistar, principalmente no ambiente de trabalho. \u201cMelhorou para os gays menos afeminados. Queremos, enquanto travestis, trabalhar com roupas que nos sentimos bem e poder usar banheiros femininos, pois tem mulheres que n\u00e3o aceitam que a gente use o mesmo banheiro. Isso ainda precisamos avan\u00e7ar.<br>Em outros pa\u00edses, como nos Estados Unidos onde uma trans trabalha na NASA, \u00e9 mais comum ter travestis em ambiente de trabalho e o Brasil vendo isso, come\u00e7a a abrir a mente\u201d, completou.<\/p>\n\n\n\n<p>Coordenadora de um n\u00facleo LGBTQIA+ da Prefeitura de Maric\u00e1, Lunah Lima, disse que a exibi\u00e7\u00e3o de um filme sobre uma travesti negra e perif\u00e9rica \u00e9 fundamental para consolidar a luta do movimento LGBTQIA+. \u201cDesmitifica o que \u00e9 o travesti e o transsexual no mundo. A gente est\u00e1 onde a gente quer. Hoje dar entrevista para um meio de comunica\u00e7\u00e3o podendo falar abertamente sobre o que \u00e9 ser uma mulher transsexual \u00e9 muito importante, mas a gente ainda quer conquistar mais espa\u00e7o. Queremos cargos de lideran\u00e7a e respeito que \u00e9 a palavra chave de todo e qualquer movimento\u201d, declarou.<\/p>\n\n\n\n<p>Dia da Visibilidade Trans<\/p>\n\n\n\n<p>O Dia Nacional da Visibilidade Trans \u00e9 comemorado no dia 29 de janeiro. A data foi celebrada pela primeira vez em 2004 com um ato em Bras\u00edlia para o lan\u00e7amento da campanha \u201cTravesti e Respeito\u201d, que foi um marco na hist\u00f3ria do movimento contra a transfobia e na luta por direitos. A partir da\u00ed, foi escolhida a data e definido o \u201cJaneiro Lil\u00e1s\u201d como o m\u00eas dedicado \u00e0 visibilidade dos transsexuais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Participa\u00e7\u00e3o Popular, Direitos Humanos e Mulher, realizou neste domingo (29\/01), na<\/p>\n","protected":false},"author":1,"featured_media":48117,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-48115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=48115"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48115\/revisions"}],"predecessor-version":[{"id":48118,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48115\/revisions\/48118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/48117"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=48115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=48115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=48115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}