{"id":48630,"date":"2023-02-25T11:43:09","date_gmt":"2023-02-25T14:43:09","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=48630"},"modified":"2023-02-25T11:43:09","modified_gmt":"2023-02-25T14:43:09","slug":"acidente-deixa-homem-ferido-em-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/02\/25\/acidente-deixa-homem-ferido-em-itaipuacu\/","title":{"rendered":"ACIDENTE DEIXA HOMEM FERIDO EM ITAIPUA\u00c7U"},"content":{"rendered":"\n<p>Um acidente aconteceu na tarde desta Sexta-feira, 24\/02, e um homem foi gravemente ferido<\/p>\n\n\n\n<p>O acidente aconteceu na esquina da rua 59 com a 35 no Jardim Atlantico em Itaipua\u00e7u<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es um carro bateu na moto em que o Fernando Cabral da Costa Barros, de 24 anos estava<\/p>\n\n\n\n<p>Fernando foi levado pro Che guevara, mas precisou ser transferido para o Alberto Torres em estado grave<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente aconteceu na tarde desta Sexta-feira, 24\/02, e um homem foi gravemente ferido O acidente aconteceu na esquina da<\/p>\n","protected":false},"author":1,"featured_media":48629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-48630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=48630"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48630\/revisions"}],"predecessor-version":[{"id":48631,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/48630\/revisions\/48631"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/48629"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=48630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=48630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=48630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}