{"id":49150,"date":"2023-03-21T20:31:30","date_gmt":"2023-03-21T23:31:30","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=49150"},"modified":"2023-04-01T03:10:56","modified_gmt":"2023-04-01T06:10:56","slug":"alameda-sera-fechada-nesta-quarta-feira-devido-manifestacao","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/03\/21\/alameda-sera-fechada-nesta-quarta-feira-devido-manifestacao\/","title":{"rendered":"ALAMEDA SER\u00c1 FECHADA NESTA QUARTA-FEIRA DEVIDO MANIFESTA\u00c7\u00c3O"},"content":{"rendered":"\n<p>Segundo informa\u00e7\u00f5es, funcion\u00e1rios do Hospital Azevedo Lima est\u00e3o sem receber seu pagamento. E em forma de protesto estar\u00e3o realizando uma manifesta\u00e7\u00e3o fechando a Alameda S\u00e3o Boaventura, nesta quarta-feira, 22, a partir das 6h da manh\u00e3.<\/p>\n\n\n\n<p>&#8220;Quem passa por l\u00e1 em dire\u00e7\u00e3o ao Rio, mude o percurso. Ningu\u00e9m recebeu o pagamento do m\u00eas. Foram todos desligados do Instituto S\u00f3crates Guanaes (ISG) e ningu\u00e9m recebeu a revis\u00e3o. Esperamos o apoio da popula\u00e7\u00e3o.&#8221;, diz um manifestante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo informa\u00e7\u00f5es, funcion\u00e1rios do Hospital Azevedo Lima est\u00e3o sem receber seu pagamento. E em forma de protesto estar\u00e3o realizando uma<\/p>\n","protected":false},"author":1,"featured_media":49149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-49150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=49150"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49150\/revisions"}],"predecessor-version":[{"id":49151,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49150\/revisions\/49151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/49149"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=49150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=49150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=49150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}