{"id":4960,"date":"2019-12-02T22:54:32","date_gmt":"2019-12-03T01:54:32","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=4960"},"modified":"2019-12-02T22:54:34","modified_gmt":"2019-12-03T01:54:34","slug":"educacao-usa-ferramenta-nutricional-para-adequar-merenda-dos-alunos","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/12\/02\/educacao-usa-ferramenta-nutricional-para-adequar-merenda-dos-alunos\/","title":{"rendered":"EDUCA\u00c7\u00c3O USA FERRAMENTA NUTRICIONAL PARA ADEQUAR MERENDA DOS ALUNOS"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"611\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-02-at-15.40.13-1024x611.jpeg\" alt=\"\" class=\"wp-image-4961\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-02-at-15.40.13-1024x611.jpeg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-02-at-15.40.13-300x179.jpeg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-02-at-15.40.13-768x458.jpeg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/WhatsApp-Image-2019-12-02-at-15.40.13.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A equipe de nutri\u00e7\u00e3o da Secretaria de Educa\u00e7\u00e3o de Maric\u00e1 est\u00e1 come\u00e7ando a utilizar um sistema de dados pioneiro que pretende adequar a alimenta\u00e7\u00e3o dos 21.194 alunos da rede municipal de ensino, levando em conta o perfil de cada um deles.<\/p>\n\n\n\n<p>A ferramenta, que consta do sistema Sigelu, est\u00e1 sendo utilizada em car\u00e1ter experimental do CEIM Ondina de Oliveira Coelho, CEM Joana Benedicta Rangel, EM Carlos Magno Legentil de Matos (essas no Centro), EM Jacyntho Luiz Caetano (Caju) e EM Ant\u00f4nio Rufino (Gamboa). Os dados colhidos incluem peso, altura, tipo sangu\u00edneo e se a crian\u00e7a apresenta algum tipo de alergia alimentar.<\/p>\n\n\n\n<p>Nesta segunda-feira (02\/12), o grupo de nutri\u00e7\u00e3o visitou o CEIM Ondina de Oliveira Coelho para avaliar meninos e meninas das turmas de pr\u00e9-escolar logo ap\u00f3s o almo\u00e7o deles. De acordo com a coordenadora de nutri\u00e7\u00e3o da secretaria, Lourici Bittencourt, o uso ser\u00e1 estendido para todas as 64 unidades da rede em 2020, mas os testes v\u00e3o servir para avaliar a efic\u00e1cia da coleta de dados, que v\u00e3o integrar um perfil completo de cada aluno.<\/p>\n\n\n\n<p>\u201cAl\u00e9m de quest\u00f5es como o poss\u00edvel sobrepeso ou desnutri\u00e7\u00e3o de alguns deles, vamos poder identificar, por exemplo, se algu\u00e9m tem alergia a gl\u00faten sem que haja um laudo apontando. Os dados ser\u00e3o mostrados aos pais para que sejam levados ao m\u00e9dico da crian\u00e7a. \u00c9 uma inova\u00e7\u00e3o para n\u00f3s e para a escola, que nos dar\u00e1 mais conhecimento sobre nossos alunos e mais precis\u00e3o do que antes nas informa\u00e7\u00f5es\u201d, destacou Lourici, que teve o aux\u00edlio da tamb\u00e9m nutricionista Juliana Carvalho.<\/p>\n\n\n\n<p>Para a diretora da unidade, Karina Figueira, o sistema tem ainda um importante aspecto democr\u00e1tico. \u201cVoc\u00ea ouve diretamente do aluno como eles receberam aquele prato, qual foi a aceita\u00e7\u00e3o conforme for inserido no card\u00e1pio, realmente \u00e9 algo in\u00e9dito\u201d, ressaltou ela. Na parte de alimenta\u00e7\u00e3o, o sistema tem ainda outras ferramentas como a de controle de estoque em cada unidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe de nutri\u00e7\u00e3o da Secretaria de Educa\u00e7\u00e3o de Maric\u00e1 est\u00e1 come\u00e7ando a utilizar um sistema de dados pioneiro que<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-4960","post","type-post","status-publish","format-standard","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/4960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=4960"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/4960\/revisions"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=4960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=4960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=4960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}