{"id":49933,"date":"2023-04-25T13:51:10","date_gmt":"2023-04-25T16:51:10","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=49933"},"modified":"2023-04-30T23:06:36","modified_gmt":"2023-05-01T02:06:36","slug":"prefeitura-promove-segundo-marica-em-danca","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/04\/25\/prefeitura-promove-segundo-marica-em-danca\/","title":{"rendered":"Prefeitura promove segundo Maric\u00e1 em Dan\u00e7a"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir=\"auto\">\n<div>\n<div class=\"gmail_quote\">\n<div dir=\"ltr\">\n<p><i>Evento acontece no s\u00e1bado (29\/04), a partir das 16h, na Lona Cultural de Itaipua\u00e7u<\/i><\/p>\n<p>A Prefeitura de Maric\u00e1, por meio da Secretaria de Cultura, promove no s\u00e1bado (29\/04), o segundo \u201cMaric\u00e1 em Dan\u00e7a\u201d, onde somente os artistas locais da cidade ir\u00e3o se apresentar, na Lona Ac\u00fastica e Cultural de Itaipua\u00e7u. O evento come\u00e7a \u00e0s 16h e tem o objetivo de disseminar a dan\u00e7a na cidade e formar p\u00fablico para o g\u00eanero art\u00edstico em comemora\u00e7\u00e3o ao Dia Internacional da Dan\u00e7a, incentivando os grupos, companhias e escola da cidade. As apresenta\u00e7\u00f5es ser\u00e3o nas categorias \u00a0baby-class, \u00a0infantil, infanto juvenil, juvenil \u00a0e adulto.<\/p>\n<p>\u201cO Maric\u00e1 em Dan\u00e7a \u00e9 um selo da Secretaria de Cultura que tem a finalidade de valorizar os artistas da cidade, colocando no palco dos nossos equipamentos para dar dimens\u00e3o para nossos talentos\u201d, \u00a0comentou o secret\u00e1rio de Cultura, Sady Bianchin.<\/p>\n<p>O evento promove a apresenta\u00e7\u00e3o de diferentes coreografias e tem o intuito de estabelecer um interc\u00e2mbio cultural, a integra\u00e7\u00e3o e acessibilidade da comunidade de modo geral, al\u00e9m de criar oportunidades aos artistas de mostrarem seus trabalhos e revelarem seus talentos. <\/p>\n<p>O coordenador de dan\u00e7a da Secretaria de Cultura, Leandro Dasilva, comentou que essa edi\u00e7\u00e3o ser\u00e1 destinada, somente, aos artistas maricaenses. <\/p>\n<p>\u201cEste evento est\u00e1 destinado somente aos artistas locais da cidade, para que possam ter oportunidade de mostrar \u00e0 popula\u00e7\u00e3o o que Maric\u00e1 tem de oferecer de dan\u00e7a e tamb\u00e9m um modo de \u00a0empoderar e promover nossos artistas\u201d, disse.<\/p>\n<div><\/div>\n<div><b>Foto em anexo &#8211;\u00a0<\/b><\/div>\n<div><b>II Dan\u00e7a em Maric\u00e1 &#8211; Divulga\u00e7\u00e3o<\/b><\/div>\n<div>\n<div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div id='gallery-1' class='gallery galleryid-49933 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maricatotal.com.br\/site\/2023\/04\/25\/prefeitura-promove-segundo-marica-em-danca\/ii-marica-em-danca-divulgacao\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/04\/II-Marica-em-Danca-Divulgacao-800x445.jpeg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Evento acontece no s\u00e1bado (29\/04), a partir das 16h, na Lona Cultural de Itaipua\u00e7u A Prefeitura de Maric\u00e1, por meio<\/p>\n","protected":false},"author":1,"featured_media":49934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-49933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=49933"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49933\/revisions"}],"predecessor-version":[{"id":50236,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/49933\/revisions\/50236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/49934"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=49933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=49933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=49933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}