{"id":50322,"date":"2023-05-01T12:53:58","date_gmt":"2023-05-01T15:53:58","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=50322"},"modified":"2023-05-01T12:54:25","modified_gmt":"2023-05-01T15:54:25","slug":"comitiva-de-marica-participa-de-evento-pelos-25-anos-do-banco-palmas-no-ceara","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/05\/01\/comitiva-de-marica-participa-de-evento-pelos-25-anos-do-banco-palmas-no-ceara\/","title":{"rendered":"Comitiva de Maric\u00e1 participa de evento pelos 25 anos do Banco Palmas, no Cear\u00e1"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir='auto'>\n<div class=\"gmail_quote\" dir=\"auto\"><\/p>\n<blockquote class=\"quote\" style=\"margin:0 0 0 .8ex;border-left:1px #ccc solid;padding-left:1ex\">\n<div dir=\"ltr\">Comemora\u00e7\u00e3o marca a experi\u00eancia do primeiro banco comunit\u00e1rio do pa\u00eds, que &nbsp;inspirou a cria\u00e7\u00e3o da moeda social mumbuca<\/p>\n<p>A Prefeitura de Maric\u00e1 enviou uma comitiva \u00e0 Fortaleza, no Cear\u00e1, para partcipar do evento em comemora\u00e7\u00e3o pelos 25 anos do Banco Palmas, o primeiro banco comunit\u00e1rio do Brasil, que serviu de inspira\u00e7\u00e3o para a cria\u00e7\u00e3o da moeda social mumbuca. Al\u00e9m de visitar uma comunidade na periferia, os representantes da prefeitura participaram &nbsp; na quinta-feira (27\/04) da 4\u00aa mesa de debates do semin\u00e1rio, com o tema \u201cOrquestra\u00e7\u00e3o de pol\u00edticas p\u00fablicas para o bem viver: as experi\u00eancias das Prefeituras de Maric\u00e1 e do Rio de Janeiro\/RJ\u201d.<\/p>\n<p>Coordenadora de Economia Solid\u00e1ria do Maranh\u00e3o e da rede de gestores, Jord\u00e2nia Pessoa mediou o debate, no qual participaram o secret\u00e1rio de Economia Solid\u00e1ria de Maric\u00e1, Adalton Mendon\u00e7a; o secret\u00e1rio de Desenvolvimento Econ\u00f4mico de Maric\u00e1, Igor Sardinha; o superintendente da Companhia de Desenvolvimento de Maric\u00e1 (Codemar), Danilo Pitarello; e o secret\u00e1rio de Desenvolvimento Econ\u00f4mico Solid\u00e1rio do Rio de Janeiro, Diego Zeidan, que j\u00e1 ocupou cargo de secret\u00e1rio de Economia Solid\u00e1ria em Maric\u00e1 e est\u00e1 licenciado do cargo de vice-prefeito.<\/p>\n<p>O programa Sim, eu Posso, de erradica\u00e7\u00e3o do analfabetismo na cidade; Mumbuca Futuro; e as iniciativas de seguran\u00e7a alimentar, como o Restaurante Municipal Mauro Alem\u00e3o e as Pra\u00e7as Agroecol\u00f3gicas, os programas Horta em casa e o Bem Viver Alimentar, foram alguns dos projetos de Maric\u00e1 citados durante a apresenta\u00e7\u00e3o da comitiva no semin\u00e1rio.<\/p>\n<p>\u201cMaric\u00e1 brilhou pela excel\u00eancia na administra\u00e7\u00e3o p\u00fablica solid\u00e1ria. Falamos sobre a experi\u00eancia exitosa de Maric\u00e1 ao longo desses quase dez anos, desde a implementa\u00e7\u00e3o do banco comunit\u00e1rio na cidade at\u00e9 os dias atuais em que a moeda beneficia mais de 42 mil moradores em situa\u00e7\u00e3o de vulnerabilidade social\u201d, explica o secret\u00e1rio de Economia Solid\u00e1ria de Maric\u00e1, Adalton Mendon\u00e7a.<\/p>\n<p>A presidente do Banco Mumbuca de Maric\u00e1, Manuela Mello; e a Irm\u00e3 Lourdes, lideran\u00e7a de Economia Solid\u00e1ria, tamb\u00e9m estiveram presentes na comemora\u00e7\u00e3o.<\/p>\n<div><\/div>\n<div><\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<div id='gallery-1' class='gallery galleryid-50322 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maricatotal.com.br\/site\/2023\/05\/01\/comitiva-de-marica-participa-de-evento-pelos-25-anos-do-banco-palmas-no-ceara\/whatsapp-image-2023-04-29-at-21-33-41\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-04-29-at-21.33.41-800x445.jpeg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-04-29-at-21.33.41-800x445.jpeg 800w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-04-29-at-21.33.41-300x168.jpeg 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Comemora\u00e7\u00e3o marca a experi\u00eancia do primeiro banco comunit\u00e1rio do pa\u00eds, que &nbsp;inspirou a cria\u00e7\u00e3o da moeda social mumbuca A Prefeitura<\/p>\n","protected":false},"author":1,"featured_media":50323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-50322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/50322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=50322"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/50322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/50323"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=50322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=50322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=50322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}