{"id":50467,"date":"2023-05-05T14:32:14","date_gmt":"2023-05-05T17:32:14","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=50467"},"modified":"2023-05-05T14:32:39","modified_gmt":"2023-05-05T17:32:39","slug":"prefeitura-de-marica-assina-convenio-com-biocubafarma-para-pesquisa-e-producao-de-vacinas-e-remedios-2","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/05\/05\/prefeitura-de-marica-assina-convenio-com-biocubafarma-para-pesquisa-e-producao-de-vacinas-e-remedios-2\/","title":{"rendered":"Prefeitura de Maric\u00e1 assina conv\u00eanio com BioCubaFarma para pesquisa e produ\u00e7\u00e3o de vacinas e rem\u00e9dios"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir='auto'>\n<div dir=\"auto\" class=\"elided-text\"><\/p>\n<blockquote style=\"margin:0 0 0 0.8ex;border-left:1px #ccc solid;padding-left:1ex\">\n<div dir=\"ltr\"><b>Prefeitura de Maric\u00e1 assina conv\u00eanio com BioCubaFarma para pesquisa e produ\u00e7\u00e3o de vacinas e rem\u00e9dios<\/b><br \/><i>Centro Binacional Brasil-Cuba ser\u00e1 criado para desenvolvimento de pesquisa e inova\u00e7\u00e3o em biotecnologia<br \/><\/i><br \/>A Prefeitura de Maric\u00e1 assinou nesta quinta-feira (04\/05) um termo de coopera\u00e7\u00e3o t\u00e9cnica com o governo cubano para cria\u00e7\u00e3o de um Centro Binacional Brasil-Cuba para desenvolvimento de pesquisa e inova\u00e7\u00e3o em biotecnologia, que ser\u00e1 instalado em Maric\u00e1. O documento prev\u00ea a realiza\u00e7\u00e3o de pesquisas para produ\u00e7\u00e3o de vacinas e f\u00e1rmacos para tratamento de doen\u00e7as emergentes e reemergentes, al\u00e9m de estudos relacionados aos medicamentos produzidos pela BioCubaFarma.<\/p>\n<p>H\u00e1 pouco mais de um m\u00eas, o presidente da BioCubaFarma esteve no Brasil em reuni\u00e3o com a comitiva de Maric\u00e1. Agora, recebendo o grupo, Eduardo Mart\u00ednez D\u00edaz ressaltou que a parceria consolida uma estrat\u00e9gia de interc\u00e2mbio entre os pa\u00edses. &#8220;Estamos muito contentes por avan\u00e7ar nessa coopera\u00e7\u00e3o com Maric\u00e1. Essa parceria ir\u00e1 ajudar muitos brasileiros e cubanos&#8221;, disse o presidente da BioCubaFarma.<\/p>\n<p>O presidente do Instituto de Ci\u00eancia Tecnologia e Inova\u00e7\u00e3o de Maric\u00e1 (ICTIM), Carlos Senna, destacou que a parceria com o \u00f3rg\u00e3o cubano respalda o munic\u00edpio na \u00e1rea do conhecimento em biotecnologia. \u201cMaric\u00e1 est\u00e1 atenta aos processos na \u00e1rea de sa\u00fade e sabe que h\u00e1 in\u00fameras possibilidades para alavancar tratamentos de forma inovadora\u201d, afirmou Senna.<\/p>\n<p>Para o subsecret\u00e1rio municipal de Sa\u00fade, Marcelo Velho, conhecer o desenvolvimento da ind\u00fastria biotecnol\u00f3gica cubana \u00e9 importante para Maric\u00e1, que tem apostado em inova\u00e7\u00e3o na \u00e1rea. &#8220;Esta ser\u00e1 uma grande oportunidade que teremos para retomar a colabora\u00e7\u00e3o cient\u00edfica com Cuba em alto n\u00edvel&#8221;, ressaltou.<\/p>\n<p>Participam tamb\u00e9m da miss\u00e3o em Havana, capital cubana, o presidente da Financiadora de Estudos e Projetos (Finep), Celso Pansera; o diretor de Administra\u00e7\u00e3o, Or\u00e7amento e Finan\u00e7as do ICTIM, Amaury Vicente; e o professor da Universidade Federal do Rio de Janeiro (UFRJ), Am\u00edlcar Tanuri, que \u00e9 consultor do ICTIM.<br clear=\"all\"><\/p>\n<div><\/div>\n<p><\/div>\n<\/blockquote>\n<\/div>\n<p><\/div>\n<div id='gallery-1' class='gallery galleryid-50467 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maricatotal.com.br\/site\/2023\/05\/05\/prefeitura-de-marica-assina-convenio-com-biocubafarma-para-pesquisa-e-producao-de-vacinas-e-remedios-2\/img-20230504-wa0059-1024x768-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/05\/IMG-20230504-WA0059-1024x768-1-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prefeitura de Maric\u00e1 assina conv\u00eanio com BioCubaFarma para pesquisa e produ\u00e7\u00e3o de vacinas e rem\u00e9diosCentro Binacional Brasil-Cuba ser\u00e1 criado para<\/p>\n","protected":false},"author":1,"featured_media":50468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-50467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/50467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=50467"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/50467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/50468"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=50467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=50467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=50467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}