{"id":53425,"date":"2023-07-08T09:34:06","date_gmt":"2023-07-08T12:34:06","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=53425"},"modified":"2023-07-17T14:42:07","modified_gmt":"2023-07-17T17:42:07","slug":"vigilante-de-marica-e-alvo-de-inquerito-por-suspeita-de-tentativa-de-envenenamento-do-proprio-filho","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/07\/08\/vigilante-de-marica-e-alvo-de-inquerito-por-suspeita-de-tentativa-de-envenenamento-do-proprio-filho\/","title":{"rendered":"Vigilante de Maric\u00e1 \u00e9 alvo de inqu\u00e9rito por suspeita de tentativa de envenenamento do pr\u00f3prio filho"},"content":{"rendered":"\n<p>A Delegacia de Maric\u00e1 abriu um inqu\u00e9rito para investigar um vigilante acusado de tentar envenenar o pr\u00f3prio filho beb\u00ea, no bairro de Cordeirinho. O caso ocorreu na tarde desta ter\u00e7a-feira, 05.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o homem teria aproveitado o momento em que a m\u00e3e estava ausente no quarto para tentar envenenar o beb\u00ea com um l\u00edquido incolor. A m\u00e3e percebeu algo errado com a crian\u00e7a, retirou-a dos bra\u00e7os do pai e dirigiu-se ao Posto de Sa\u00fade do bairro.<\/p>\n\n\n\n<p>Diante da falta de melhora no estado de sa\u00fade do beb\u00ea, os socorristas do SAMU foram acionados e encaminharam a crian\u00e7a para o Hospital Municipal Conde Modesto Leal, no Centro de Maric\u00e1. Na unidade hospitalar, a equipe m\u00e9dica realizou a lavagem g\u00e1strica para eliminar qualquer subst\u00e2ncia t\u00f3xica.<\/p>\n\n\n\n<p>O acusado, identificado como Rhamon Alves, de 33 anos, foi procurado pelos agentes da Guarda Municipal, mas conseguiu fugir. Al\u00e9m das acusa\u00e7\u00f5es de envenenamento, o homem tamb\u00e9m \u00e9 suspeito de amea\u00e7ar a ex-companheira em diversas ocasi\u00f5es, afirmando que a crian\u00e7a n\u00e3o \u00e9 seu filho. As autoridades est\u00e3o empenhadas em localiz\u00e1-lo para dar prosseguimento \u00e0s investiga\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Delegacia de Maric\u00e1 abriu um inqu\u00e9rito para investigar um vigilante acusado de tentar envenenar o pr\u00f3prio filho beb\u00ea, no<\/p>\n","protected":false},"author":1,"featured_media":46349,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-53425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=53425"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53425\/revisions"}],"predecessor-version":[{"id":53427,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53425\/revisions\/53427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/46349"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=53425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=53425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=53425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}