{"id":5359,"date":"2019-12-16T18:16:14","date_gmt":"2019-12-16T21:16:14","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=5359"},"modified":"2019-12-16T18:16:16","modified_gmt":"2019-12-16T21:16:16","slug":"nao-havera-expediente-nos-dias-24-e-31-de-dezembro","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2019\/12\/16\/nao-havera-expediente-nos-dias-24-e-31-de-dezembro\/","title":{"rendered":"N\u00c3O HAVER\u00c1 EXPEDIENTE NOS DIAS 24 E 31 DE DEZEMBRO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/CDB499C7-0384-4EDB-82B6-7ED50586D8CB-1024x768.jpeg\" alt=\"\" class=\"wp-image-5360\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/CDB499C7-0384-4EDB-82B6-7ED50586D8CB-1024x768.jpeg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/CDB499C7-0384-4EDB-82B6-7ED50586D8CB-300x225.jpeg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/CDB499C7-0384-4EDB-82B6-7ED50586D8CB-768x576.jpeg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2019\/12\/CDB499C7-0384-4EDB-82B6-7ED50586D8CB.jpeg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por conta das festas de fim de ano, n\u00e3o haver\u00e1 expediente na Prefeitura de Maric\u00e1 nos dias 24\/12 e 31\/12. O decreto municipal n\u00ba 419 de 19 de novembro de 2019 foi assinado pelo prefeito Fabiano Horta e publicado no Jornal Oficial do Munic\u00edpio (JOM) no dia 04\/12.<\/p>\n\n\n\n<p>O expediente ser\u00e1 normal, entretanto, sob a responsabilidade dos respectivos chefes, nas reparti\u00e7\u00f5es cujas atividades n\u00e3o possam ser suspensas, em virtude de exig\u00eancias t\u00e9cnicas ou por motivo de interesse p\u00fablico.<\/p>\n\n\n\n<p>Entre os servi\u00e7os essenciais est\u00e3o o Hospital Municipal Conde Modesto Leal (Centro), a Unidade de Pronto Atendimento (UPA) de Ino\u00e3 e a&nbsp;Unidade de Sa\u00fade 24h Santa Rita (Itaipua\u00e7u), al\u00e9m dos&nbsp;plant\u00f5es 24h da Defesa Civil, da Guarda Municipal e os servi\u00e7os de coleta de lixo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por conta das festas de fim de ano, n\u00e3o haver\u00e1 expediente na Prefeitura de Maric\u00e1 nos dias 24\/12 e 31\/12.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[17],"tags":[],"class_list":["post-5359","post","type-post","status-publish","format-standard","hentry","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/5359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=5359"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/5359\/revisions"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=5359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=5359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=5359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}