{"id":53634,"date":"2023-07-13T16:51:42","date_gmt":"2023-07-13T19:51:42","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=53634"},"modified":"2023-07-17T14:49:35","modified_gmt":"2023-07-17T17:49:35","slug":"comocao-e-dor-marcaram-o-enterro-do-estudante-que-foi-morto-durante-tiroteio-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/07\/13\/comocao-e-dor-marcaram-o-enterro-do-estudante-que-foi-morto-durante-tiroteio-em-marica\/","title":{"rendered":"Como\u00e7\u00e3o e dor marcaram o enterro do estudante que foi morto durante tiroteio em Maric\u00e1"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir=\"auto\">\n<div>\n<div class=\"gmail_quote\">\n<div class=\"gmail_quote\"><br type=\"attribution\"><\/p>\n<blockquote style=\"margin:0 0 0 .8ex;border-left:1px #ccc solid;padding-left:1ex\">\n<div dir=\"auto\">\n<div dir=\"auto\">Enterro de Dijalma de Azevedo Clemente, crian\u00e7a v\u00edtima de tiroteio no complexo habitacional &#39;Minha Casa, Minha Vida&#39; em Ino\u00e3, ocorreu na tarde desta quinta-feira, 13, no Cemit\u00e9rio de Maric\u00e1.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Durante o vel\u00f3rio, familiares e amigos da crian\u00e7a manifestaram grande como\u00e7\u00e3o e protestaram contra o tr\u00e1gico acontecimento. Dijalma foi morto por um disparo durante uma a\u00e7\u00e3o da Pol\u00edcia Militar na manh\u00e3 de quarta-feira, 12.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Em comunicado enviado pela Assessoria de Imprensa, a Pol\u00edcia Militar declarou que os policiais da Companhia de Maric\u00e1, pertencentes ao 12\u00ba Batalh\u00e3o de Niter\u00f3i, estavam realizando policiamento na Estrada do Boque Fundo quando foram atacados por criminosos armados nas proximidades do condom\u00ednio.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Dijalma de Azevedo Clemente ter\u00e1 seu nome inserido no memorial da Rio de Paz, localizado na Lagoa Rodrigo de Freitas, Zona Sul do Rio de Janeiro. O memorial honra as crian\u00e7as e adolescentes v\u00edtimas de balas perdidas em todo o estado.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">O caso est\u00e1 sendo investigado pela Delegacia de Homic\u00eddios de Niter\u00f3i, S\u00e3o Gon\u00e7alo, Itabora\u00ed e Maric\u00e1.<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<p><\/div>\n<\/div>\n<\/div>\n<div id='gallery-1' class='gallery galleryid-53634 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maricatotal.com.br\/site\/2023\/07\/13\/comocao-e-dor-marcaram-o-enterro-do-estudante-que-foi-morto-durante-tiroteio-em-marica\/img-20230713-wa0025\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/07\/IMG-20230713-WA0025-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Enterro de Dijalma de Azevedo Clemente, crian\u00e7a v\u00edtima de tiroteio no complexo habitacional &#39;Minha Casa, Minha Vida&#39; em Ino\u00e3, ocorreu<\/p>\n","protected":false},"author":1,"featured_media":53635,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-53634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=53634"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53634\/revisions"}],"predecessor-version":[{"id":53785,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/53634\/revisions\/53785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/53635"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=53634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=53634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=53634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}