{"id":54518,"date":"2023-07-31T18:49:27","date_gmt":"2023-07-31T21:49:27","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=54518"},"modified":"2023-07-31T18:49:27","modified_gmt":"2023-07-31T21:49:27","slug":"novos-comandantes-da-pm-de-marica-tracam-plano-para-reforcar-seguranca-na-cidade","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/07\/31\/novos-comandantes-da-pm-de-marica-tracam-plano-para-reforcar-seguranca-na-cidade\/","title":{"rendered":"Novos comandantes da PM de Maric\u00e1 tra\u00e7am plano para refor\u00e7ar seguran\u00e7a na cidade"},"content":{"rendered":"\n<p>Nesta segunda-feira, 31, os novos comandantes da 6\u00aa Companhia de Maric\u00e1, major Davi e sub-comandante tenente Braga, realizaram uma reuni\u00e3o com os policiais atuantes na cidade para discutir a nova gest\u00e3o da CIA.<div id=\"__next\"><div class=\"overflow-hidden w-full h-full relative flex z-0\"><div class=\"relative flex h-full max-w-full flex-1 overflow-hidden\"><div class=\"flex h-full max-w-full flex-1 flex-col\"><main class=\"relative h-full w-full transition-width flex flex-col overflow-auto items-stretch flex-1\"><div class=\"flex-1 overflow-hidden\"><div class=\"react-scroll-to-bottom--css-dsiom-79elbk h-full dark:bg-gray-800\"><div class=\"react-scroll-to-bottom--css-dsiom-1n7m0yu\"><div class=\"flex flex-col text-sm dark:bg-gray-800\"><div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-[#444654]\"><div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-[38rem] xl:max-w-3xl md:py-6 lg:px-0 m-auto\"><div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\"><div class=\"flex flex-grow flex-col gap-3\"><div class=\"min-h-[20px] flex items-start overflow-x-auto whitespace-pre-wrap break-words\"><div class=\"markdown prose w-full break-words dark:prose-invert light\"><p>Durante a reuni\u00e3o, os comandantes destacaram a import\u00e2ncia de aumentar as abordagens a ve\u00edculos no munic\u00edpio, visando reduzir os \u00edndices de furtos e roubos de autom\u00f3veis na regi\u00e3o, proporcionando maior sensa\u00e7\u00e3o de seguran\u00e7a para os moradores.<\/p><p>Tamb\u00e9m foi informado que a dupla realizou um levantamento dos hor\u00e1rios mais cr\u00edticos em que ocorrem crimes na cidade, e que o policiamento ser\u00e1 refor\u00e7ado durante essas horas espec\u00edficas, com o objetivo de diminuir assaltos e invas\u00f5es a resid\u00eancias.<\/p><p>Outra iniciativa abordada na reuni\u00e3o foi o pedido ao comandante do Batalh\u00e3o de Niter\u00f3i (12\u00ba BPM) para aumentar o efetivo policial em Maric\u00e1, considerando o aumento populacional e a defasagem do n\u00famero de policiais de plant\u00e3o.<\/p><p>Os comandantes enfatizaram o comprometimento em trabalhar intensamente para frear o crescimento do \u00edndice de criminalidade, evitando que o munic\u00edpio acompanhe o ritmo das cidades vizinhas. Com a nova gest\u00e3o, espera-se fortalecer a seguran\u00e7a e garantir o bem-estar da popula\u00e7\u00e3o maricaense.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/main><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta segunda-feira, 31, os novos comandantes da 6\u00aa Companhia de Maric\u00e1, major Davi e sub-comandante tenente Braga, realizaram uma reuni\u00e3o<\/p>\n","protected":false},"author":1,"featured_media":54521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14,1],"tags":[],"class_list":["post-54518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/54518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=54518"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/54518\/revisions"}],"predecessor-version":[{"id":54522,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/54518\/revisions\/54522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/54521"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=54518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=54518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=54518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}