{"id":58738,"date":"2023-11-25T10:11:44","date_gmt":"2023-11-25T13:11:44","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=58738"},"modified":"2023-11-25T10:16:38","modified_gmt":"2023-11-25T13:16:38","slug":"banco-mumbuca-sedia-terceiro-encontro-de-economia-solidaria","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/11\/25\/banco-mumbuca-sedia-terceiro-encontro-de-economia-solidaria\/","title":{"rendered":"Banco Mumbuca sedia terceiro encontro de economia solid\u00e1ria"},"content":{"rendered":"<div class=\"postie-post\">\n<div dir='auto'>\n<div>\n<div class=\"elided-text\">\n<blockquote style=\"margin:0 0 0 0.8ex;border-left:1px #ccc solid;padding-left:1ex\">\n<div dir=\"ltr\">\n<p>Termina neste s\u00e1bado (25\/11) a terceira edi\u00e7\u00e3o do Encontro de Gestores, Articuladores e Pesquisadores em Economia Solid\u00e1ria (EGAPES), que acontece na sede do Banco Mumbuca, no Centro de Maric\u00e1, desde a \u00faltima quinta-feira (23). O evento recebe autoridades nacionais e internacionais do setor para debater experi\u00eancias. Houve ainda atra\u00e7\u00f5es como desfiles, do tipo \u2018eco fashion\u2019, e uma edi\u00e7\u00e3o especial da feira livre solid\u00e1ria, que ocorre na esquina das ruas Hil\u00e1rio Luiz Queiroz da Silva e Eug\u00eania Modesto da Silva.<\/p>\n<p>No s\u00e1bado ser\u00e1 lan\u00e7ada a Rede Rio de Bancos Comunit\u00e1rios, que vai reunir institui\u00e7\u00f5es gestoras de moedas sociais de dez munic\u00edpios do estado. Uma das metas do grupo ser\u00e1 cobrar uma participa\u00e7\u00e3o mais efetiva do governo estadual no fomento e est\u00edmulo \u00e0 economia solid\u00e1ria. O ato simb\u00f3lico de lan\u00e7amento est\u00e1 previsto para \u00e0s 10 horas no audit\u00f3rio do banco, onde acontecem as mesas de discuss\u00e3o.<\/p>\n<p>\u201cO que fazemos aqui \u00e9 trocar experi\u00eancias e debater o movimento da economia solid\u00e1ria em escala internacional, para avaliar o que deu certo e o que deu errado em cada experi\u00eancia. S\u00f3 do estado do Esp\u00edrito Santo vieram onze bancos comunit\u00e1rios, e esse movimento acontece muito por causa de Maric\u00e1. Por isso estamos mais uma vez sediando o encontro\u201d, ressaltou a presidente do Banco Mumbuca, Manuela Mello.<\/p>\n<div><b><br \/><\/b><\/div>\n<div><\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<div id='gallery-1' class='gallery galleryid-58738 gallery-columns-3 gallery-size-colormag-featured-image'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maricatotal.com.br\/site\/2023\/11\/25\/banco-mumbuca-sedia-terceiro-encontro-de-economia-solidaria\/screenshot_20231125-101123_chrome\/'><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/11\/Screenshot_20231125-101123_Chrome-800x445.jpg\" class=\"attachment-colormag-featured-image size-colormag-featured-image\" alt=\"\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/11\/Screenshot_20231125-101123_Chrome-800x445.jpg 800w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2023\/11\/Screenshot_20231125-101123_Chrome-1078x600.jpg 1078w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Termina neste s\u00e1bado (25\/11) a terceira edi\u00e7\u00e3o do Encontro de Gestores, Articuladores e Pesquisadores em Economia Solid\u00e1ria (EGAPES), que acontece<\/p>\n","protected":false},"author":1,"featured_media":58739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-58738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/58738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=58738"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/58738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/58739"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=58738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=58738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=58738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}