{"id":59561,"date":"2023-12-23T23:41:42","date_gmt":"2023-12-24T02:41:42","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=59561"},"modified":"2023-12-23T23:41:44","modified_gmt":"2023-12-24T02:41:44","slug":"homem-e-detido-por-agredir-companheira-e-guarda-municipal","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2023\/12\/23\/homem-e-detido-por-agredir-companheira-e-guarda-municipal\/","title":{"rendered":"Homem \u00e9 detido por agredir companheira e guarda municipal"},"content":{"rendered":"\n<p>Na noite deste s\u00e1bado, a Equipe da ROMU (Ronda Ostensiva Municipal) agiu  de forma r\u00e1pida e eficiente ao conduzir um indiv\u00edduo suspeito de  agredir sua companheira, al\u00e9m de um Guarda Municipal, \u00e0 82\u00aa Delegacia de  Pol\u00edcia.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/chat.whatsapp.com\/E36A0xCLJxl2lWrJ1ijHs3\">QUER SABER DE TUDO QUE ACONTECE NA CIDADE? CLIQUE AQUI E ENTRE NO NOSSO GRUPO DO WHATSAPP.<\/a><\/strong><\/p>\n\n\n\n<p>O caso envolveu uma situa\u00e7\u00e3o de viol\u00eancia dom\u00e9stica, na qual o suspeito  teria agredido sua parceira. Diante da gravidade do ocorrido, os agentes  da ROMU intervieram, assegurando a integridade da v\u00edtima e conduzindo o  suspeito \u00e0 delegacia para prestar esclarecimentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite deste s\u00e1bado, a Equipe da ROMU (Ronda Ostensiva Municipal) agiu de forma r\u00e1pida e eficiente ao conduzir um<\/p>\n","protected":false},"author":1,"featured_media":59563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-59561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/59561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=59561"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/59561\/revisions"}],"predecessor-version":[{"id":59564,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/59561\/revisions\/59564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/59563"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=59561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=59561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=59561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}