{"id":6099,"date":"2020-01-13T09:18:33","date_gmt":"2020-01-13T12:18:33","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=6099"},"modified":"2020-01-13T09:18:35","modified_gmt":"2020-01-13T12:18:35","slug":"prefeitura-se-pronuncia-sobre-as-fortes-chuvas","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/01\/13\/prefeitura-se-pronuncia-sobre-as-fortes-chuvas\/","title":{"rendered":"PREFEITURA SE PRONUNCIA SOBRE AS FORTES CHUVAS"},"content":{"rendered":"\n<p><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC.png\" alt=\"\" class=\"wp-image-6100\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC.png 512w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC-300x300.png 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC-150x150.png 150w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC-400x400.png 400w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/708F6B2C-0825-4A98-93BC-B42B520A30BC-500x500.png 500w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Maric\u00e1 alerta que a cidade est\u00e1 em est\u00e1gio de Aten\u00e7\u00e3o por conta das chuvas. Equipes da autarquia Servi\u00e7os de Obras de Maric\u00e1 (Somar), das secretarias de Habita\u00e7\u00e3o, Assist\u00eancia Social, Prote\u00e7\u00e3o e Defesa Civil, Tr\u00e2nsito e de Ordem P\u00fablica est\u00e3o todas nas ruas desde a madrugada para amenizar os transfornos provocados pelas chuvas que atingiram a cidade nesta segunda-feira (13\/01). A aproxima\u00e7\u00e3o de uma frente fria pelo oceano mant\u00e9m o tempo inst\u00e1vel na cidade. H\u00e1 v\u00e1rios bols\u00f5es de \u00e1gua pela cidade e o acumulado de chuvas na esta\u00e7\u00e3o pluviom\u00e9trica da Mumbuca (mede a regi\u00e3o do Centro e adjac\u00eancias) foi de 67.4mm \u00e0s 6h45min, considerado chuva de intensidade muito forte.<\/p>\n\n\n\n<p>Informamos que ainda h\u00e1 previs\u00e3o de chuva fraca a moderada, podendo ser forte de forma r\u00e1pida e isolada para as pr\u00f3ximas horas.<\/p>\n\n\n\n<p>A Secretaria de Prote\u00e7\u00e3o e Defesa Civil orienta as pessoas a evitarem deslocamentos e procurarem locais seguros. O telefone de emerg\u00eancia \u00e9 o 199.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1 alerta que a cidade est\u00e1 em est\u00e1gio de Aten\u00e7\u00e3o por conta das chuvas. Equipes da autarquia<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14,17],"tags":[],"class_list":["post-6099","post","type-post","status-publish","format-standard","hentry","category-bairros","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/6099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=6099"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/6099\/revisions"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=6099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=6099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=6099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}