{"id":61034,"date":"2024-02-14T15:10:21","date_gmt":"2024-02-14T18:10:21","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=61034"},"modified":"2024-02-15T14:48:28","modified_gmt":"2024-02-15T17:48:28","slug":"homem-e-preso-por-abuso-infantil-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/02\/14\/homem-e-preso-por-abuso-infantil-em-marica\/","title":{"rendered":"Homem \u00e9 preso por abuso infantil em Maric\u00e1"},"content":{"rendered":"\n<p>Um homem foi preso em Maric\u00e1 pela Pol\u00edcia Civil sob acusa\u00e7\u00e3o de abusar sexualmente de dois adolescentes. <\/p>\n\n\n\n<p>Um dos jovens filmou o ato para comprovar o abuso. As autoridades foram alertadas quando o v\u00eddeo chegou ao conhecimento do Grupamento Maria da Penha da Guarda Municipal de Maric\u00e1, que encaminhou as imagens \u00e0 delegacia. <\/p>\n\n\n\n<p>O acusado foi capturado pela equipe da 82\u00aa DP e ser\u00e1 autuado por abuso de menores, pedofilia e flagrante de estupro, sendo transferido em seguida para o sistema prisional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem foi preso em Maric\u00e1 pela Pol\u00edcia Civil sob acusa\u00e7\u00e3o de abusar sexualmente de dois adolescentes. Um dos jovens<\/p>\n","protected":false},"author":1,"featured_media":61036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14,1],"tags":[],"class_list":["post-61034","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=61034"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61034\/revisions"}],"predecessor-version":[{"id":61038,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61034\/revisions\/61038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/61036"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=61034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=61034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=61034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}