{"id":61474,"date":"2024-02-29T15:46:38","date_gmt":"2024-02-29T18:46:38","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=61474"},"modified":"2024-02-29T15:46:40","modified_gmt":"2024-02-29T18:46:40","slug":"falso-corretor-de-imoveis-aplica-golpes-em-diversas-pessoas-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/02\/29\/falso-corretor-de-imoveis-aplica-golpes-em-diversas-pessoas-em-marica\/","title":{"rendered":"Falso corretor de im\u00f3veis aplica golpes em diversas pessoas em Maric\u00e1"},"content":{"rendered":"\n<p><p>Um casal de Maric\u00e1, infelizmente, ca\u00edram em um golpe aplicado por um falso corretor de im\u00f3veis na regi\u00e3o.<\/p><\/p>\n\n\n\n<p><p>Segundo o denunciante, ele e sua esposa estavam em processo de compra de uma casa em Ara\u00e7atiba, no valor de R$300 mil, com o suposto corretor, quando perceberam que os documentos fornecidos pelo indiv\u00edduo para a conclus\u00e3o do neg\u00f3cio eram falsificados.Ap\u00f3s investiga\u00e7\u00f5es preliminares, o casal descobriu que a propriedade j\u00e1 havia sido vendida v\u00e1rias vezes para diferentes pessoas, todas v\u00edtimas do mesmo golpe, resultando na perda do dinheiro investido.<\/p><\/p>\n\n\n\n<p><p>Diante da situa\u00e7\u00e3o, o morador dirigiu-se \u00e0 Delegacia de Maric\u00e1 (82\u00aa DP) para registrar o ocorrido, dando in\u00edcio a uma investiga\u00e7\u00e3o policial. Durante o procedimento na unidade policial, foi constatado que o falso corretor j\u00e1 possu\u00eda diversas passagens pela pol\u00edcia por associa\u00e7\u00e3o criminosa, atuando em \u00e1reas como cart\u00f3rio, banco e imobili\u00e1ria.<\/p><\/p>\n\n\n\n<p><p>A pol\u00edcia est\u00e1 empenhada em esclarecer o caso e orienta a popula\u00e7\u00e3o a verificar cuidadosamente a documenta\u00e7\u00e3o e a idoneidade dos profissionais envolvidos em transa\u00e7\u00f5es imobili\u00e1rias, a fim de evitar cair em golpes semelhantes.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um casal de Maric\u00e1, infelizmente, ca\u00edram em um golpe aplicado por um falso corretor de im\u00f3veis na regi\u00e3o. Segundo o<\/p>\n","protected":false},"author":1,"featured_media":60636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14,1],"tags":[],"class_list":["post-61474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=61474"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61474\/revisions"}],"predecessor-version":[{"id":61476,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/61474\/revisions\/61476"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/60636"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=61474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=61474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=61474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}