{"id":62102,"date":"2024-03-24T15:42:54","date_gmt":"2024-03-24T18:42:54","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=62102"},"modified":"2024-03-24T15:42:55","modified_gmt":"2024-03-24T18:42:55","slug":"ictm-abre-vagas-para-cursos-de-cinemagames-e-carnaval","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/03\/24\/ictm-abre-vagas-para-cursos-de-cinemagames-e-carnaval\/","title":{"rendered":"ICTM abre vagas para cursos de cinema,games e Carnaval"},"content":{"rendered":"\n<p>A Prefeitura de Maric\u00e1, por meio da Incubadora de Inova\u00e7\u00e3o Social em Cultura, est\u00e1 oferecendo uma oportunidade \u00fanica para os moradores da cidade se capacitarem na \u00e1rea de cinema, games e Carnaval.<\/p>\n\n\n\n<p>Ao todo, s\u00e3o disponibilizadas 522 vagas em cursos com dura\u00e7\u00e3o de 5 meses, sendo que 20% delas s\u00e3o reservadas para pessoas pretas e pardas, e mais 5% para pessoas com defici\u00eancia. Esses cursos, tanto te\u00f3ricos quanto pr\u00e1ticos, s\u00e3o exclusivamente para moradores de Maric\u00e1 com idade a partir de 16 anos.<\/p>\n\n\n\n<p>Para aqueles interessados na \u00e1rea do cinema, h\u00e1 uma variedade de op\u00e7\u00f5es, incluindo realiza\u00e7\u00e3o audiovisual, assist\u00eancia de dire\u00e7\u00e3o, cinema e psicologia, dire\u00e7\u00e3o de arte, document\u00e1rio, dramaturgia e interpreta\u00e7\u00e3o, edi\u00e7\u00e3o para cinema e v\u00eddeo, fotografia para cinema e v\u00eddeo, produ\u00e7\u00e3o para cinema e v\u00eddeo, roteiros para obras audiovisuais e som para cinema e v\u00eddeo.<\/p>\n\n\n\n<p>J\u00e1 para os entusiastas de games, h\u00e1 o curso de desenvolvimento de game, enquanto para os apaixonados pelo Carnaval, os cursos dispon\u00edveis incluem Carnaval, composi\u00e7\u00e3o musical, dan\u00e7a afro, fantasias e adere\u00e7os de destaque, maquiagem e caracteriza\u00e7\u00e3o art\u00edstica, e produ\u00e7\u00e3o art\u00edstico-cultural.<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es podem ser feitas at\u00e9 segunda-feira, 25, atrav\u00e9s do site <a href=\"http:\/\/www.incubacultura.org.br\/\">www.incubacultura.org.br<\/a>. As aulas ser\u00e3o ministradas presencialmente na Rua \u00c1lvares de Castro, 699, no Centro de Maric\u00e1. Esta \u00e9 uma oportunidade imperd\u00edvel para os residentes locais se capacitarem e desenvolverem suas habilidades na \u00e1rea cultural.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Maric\u00e1, por meio da Incubadora de Inova\u00e7\u00e3o Social em Cultura, est\u00e1 oferecendo uma oportunidade \u00fanica para os<\/p>\n","protected":false},"author":1,"featured_media":57134,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14,17],"tags":[],"class_list":["post-62102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros","category-politica"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=62102"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62102\/revisions"}],"predecessor-version":[{"id":62104,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62102\/revisions\/62104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/57134"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=62102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=62102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=62102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}