{"id":62744,"date":"2024-04-21T17:00:10","date_gmt":"2024-04-21T20:00:10","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=62744"},"modified":"2024-04-21T17:06:42","modified_gmt":"2024-04-21T20:06:42","slug":"itaipuacu-recebera-feira-da-agricultura-familiar-quinzenalmente","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/04\/21\/itaipuacu-recebera-feira-da-agricultura-familiar-quinzenalmente\/","title":{"rendered":"Itaipua\u00e7u Receber\u00e1 Feira da Agricultura Familiar Quinzenalmente"},"content":{"rendered":"\n<p>O prefeito de Maric\u00e1, Fabiano Horta, anunciou neste s\u00e1bado (20) uma novidade empolgante para os moradores de Itaipua\u00e7u: a partir de maio, a Feira da Agricultura Familiar ser\u00e1 realizada na regi\u00e3o a cada quinze dias. O an\u00fancio vem ap\u00f3s o grande sucesso de p\u00fablico registrado no evento, que aconteceu pela segunda vez neste final de semana.<\/p>\n\n\n\n<p>Organizada pela Secretaria de Agricultura, Pecu\u00e1ria, Pesca e Abastecimento, a feira tem como objetivo promover e valorizar os produtos da agricultura familiar local. Localizada na Rua dos L\u00edrios, ao lado da pra\u00e7a do Barroco, a feira contou com a participa\u00e7\u00e3o de 47 feirantes, al\u00e9m de tr\u00eas barracas montadas por projetos da prefeitura.<\/p>\n\n\n\n<p>As barracas dos projetos do Instituto Cooperar apresentaram uma variedade de sementes e mudas org\u00e2nicas, enquanto a F\u00e1brica de Desidratados Pref. \u00c9dio Muniz ofereceu seus produtos desidratados. A diversidade de produtos e o apoio da comunidade demonstraram o potencial da feira como um espa\u00e7o de incentivo \u00e0 agricultura familiar e ao com\u00e9rcio local.<\/p>\n\n\n\n<p>A decis\u00e3o de tornar a feira quinzenal reflete o compromisso da administra\u00e7\u00e3o municipal em promover o desenvolvimento econ\u00f4mico sustent\u00e1vel e fortalecer os la\u00e7os entre produtores e consumidores locais. Os moradores de Itaipua\u00e7u podem aguardar uma oportunidade regular de adquirir produtos frescos, saud\u00e1veis e de qualidade diretamente dos agricultores familiares da regi\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Maric\u00e1, Fabiano Horta, anunciou neste s\u00e1bado (20) uma novidade empolgante para os moradores de Itaipua\u00e7u: a partir<\/p>\n","protected":false},"author":1,"featured_media":62746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[34,35,18],"tags":[],"class_list":["post-62744","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acidentes","category-top-stories","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=62744"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62744\/revisions"}],"predecessor-version":[{"id":62747,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/62744\/revisions\/62747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/62746"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=62744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=62744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=62744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}