{"id":63084,"date":"2024-05-07T21:34:40","date_gmt":"2024-05-08T00:34:40","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=63084"},"modified":"2024-05-09T09:19:54","modified_gmt":"2024-05-09T12:19:54","slug":"operacao-conjunta-resulta-em-prejuizo-de-r100-000-pro-trafico-apos-troca-de-tiro-em-inoa","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/05\/07\/operacao-conjunta-resulta-em-prejuizo-de-r100-000-pro-trafico-apos-troca-de-tiro-em-inoa\/","title":{"rendered":"Opera\u00e7\u00e3o conjunta resulta em preju\u00edzo de R$100.000 pro tr\u00e1fico ap\u00f3s troca de tiro em Ino\u00e3"},"content":{"rendered":"\n<p>Na tarde de hoje, uma opera\u00e7\u00e3o conjunta entre a Patamo de Niter\u00f3i e a P2 resultou em uma a\u00e7\u00e3o policial significativa na comunidade do Risca Faca, localizada em Ino\u00e3. Durante a opera\u00e7\u00e3o, dois homens adultos foram presos e um menor foi apreendido, al\u00e9m da apreens\u00e3o de armas, drogas e r\u00e1dios transmissores.<\/p>\n\n\n\n<p>De acordo com informa\u00e7\u00f5es fornecidas pelas autoridades, a a\u00e7\u00e3o ocorreu de maneira intensa, envolvendo uma troca de tiros entre os policiais e os suspeitos. Apesar da situa\u00e7\u00e3o desafiadora, os agentes conseguiram conter a resist\u00eancia dos indiv\u00edduos e efetuar as pris\u00f5es.<\/p>\n\n\n\n<p>Entre as apreens\u00f5es realizadas, destaca-se a descoberta de dois r\u00e1dios transmissores, que podem indicar a participa\u00e7\u00e3o dos suspeitos em atividades criminosas relacionadas \u00e0 comunica\u00e7\u00e3o e coordena\u00e7\u00e3o de a\u00e7\u00f5es il\u00edcitas. Al\u00e9m disso, foi encontrada uma grande quantidade de drogas, cujo valor estimado \u00e9 de aproximadamente R$100.000, demonstrando uma opera\u00e7\u00e3o de tr\u00e1fico de entorpecentes em andamento na regi\u00e3o.<\/p>\n\n\n\n<p>Ainda durante a a\u00e7\u00e3o, a pol\u00edcia tamb\u00e9m localizou uma pistola carregada, a qual pode ter sido utilizada para amea\u00e7ar e intimidar os moradores da comunidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na tarde de hoje, uma opera\u00e7\u00e3o conjunta entre a Patamo de Niter\u00f3i e a P2 resultou em uma a\u00e7\u00e3o policial<\/p>\n","protected":false},"author":1,"featured_media":63086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14,1],"tags":[],"class_list":["post-63084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=63084"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63084\/revisions"}],"predecessor-version":[{"id":63103,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63084\/revisions\/63103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/63086"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=63084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=63084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=63084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}