{"id":63813,"date":"2024-06-12T10:03:33","date_gmt":"2024-06-12T13:03:33","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=63813"},"modified":"2024-06-12T15:38:44","modified_gmt":"2024-06-12T18:38:44","slug":"moradores-do-flamengo-pedem-ajuda-da-aguas-do-rio-para-resolver-vazamento-a-mais-de-2-meses","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/06\/12\/moradores-do-flamengo-pedem-ajuda-da-aguas-do-rio-para-resolver-vazamento-a-mais-de-2-meses\/","title":{"rendered":"Moradores do Flamengo pedem ajuda da \u00c1guas do Rio para resolver vazamento a mais de 2 meses"},"content":{"rendered":"\n<p>A equipe do Maric\u00e1 Total recebeu diversas reclama\u00e7\u00f5es de moradores do bairro do Flamengo, pr\u00f3ximo ao Col\u00e9gio Cl\u00e9rio Boechat, sobre um vazamento de \u00e1gua que persiste h\u00e1 mais de dois meses na regi\u00e3o.<\/p>\n\n\n\n<p>Segundo os relatos, o problema vem causando diversos transtornos \u00e0 popula\u00e7\u00e3o local, como a forma\u00e7\u00e3o de buracos e afundamento do asfalto, colocando em risco a seguran\u00e7a de pedestres e motoristas. H\u00e1 preocupa\u00e7\u00e3o com a possibilidade de acidentes, como algu\u00e9m se ferir ao pisar no buraco ou um motociclista colidir com o obst\u00e1culo.<\/p>\n\n\n\n<p>Os moradores informam que j\u00e1 encaminharam um of\u00edcio \u00e0 \u00c1guas do Rio, empresa respons\u00e1vel pelo abastecimento de \u00e1gua na cidade, mas at\u00e9 o momento nenhuma provid\u00eancia foi tomada para solucionar o vazamento.<\/p>\n\n\n\n<p>H\u00e1 tamb\u00e9m informa\u00e7\u00f5es de que a prefeitura tem sido culpada pelo problema, mas de acordo com os relatos, a municipalidade n\u00e3o tem qualquer responsabilidade sobre o caso, uma vez que se trata de uma infraestrutura da concession\u00e1ria de \u00e1gua.<\/p>\n\n\n\n<p>Diante dessa situa\u00e7\u00e3o, a equipe do Maric\u00e1 Total solicita que a \u00c1guas do Rio envie com urg\u00eancia uma equipe t\u00e9cnica ao local para identificar a origem do vazamento e realizar os reparos necess\u00e1rios, a fim de evitar acidentes e transtornos ainda maiores \u00e0 popula\u00e7\u00e3o da regi\u00e3o.<\/p>\n\n\n\n<p>Em nota, a empresa \u00c1guas do Rio informou:<\/p>\n\n\n\n<p><em>&#8220;A \u00c1guas do Rio informa que vai enviar uma equipe ao local para verificar a ocorr\u00eancia. A empresa segue \u00e0 disposi\u00e7\u00e3o atrav\u00e9s do 0800 195 0 195, que funciona para liga\u00e7\u00f5es gratuitas e mensagens via WhatsApp.&#8221;<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe do Maric\u00e1 Total recebeu diversas reclama\u00e7\u00f5es de moradores do bairro do Flamengo, pr\u00f3ximo ao Col\u00e9gio Cl\u00e9rio Boechat, sobre<\/p>\n","protected":false},"author":1,"featured_media":63815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14],"tags":[],"class_list":["post-63813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=63813"}],"version-history":[{"count":2,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63813\/revisions"}],"predecessor-version":[{"id":63818,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/63813\/revisions\/63818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/63815"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=63813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=63813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=63813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}