{"id":64631,"date":"2024-07-21T23:54:30","date_gmt":"2024-07-22T02:54:30","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=64631"},"modified":"2024-07-21T23:54:31","modified_gmt":"2024-07-22T02:54:31","slug":"policia-militar-anuncia-abertura-de-tres-novos-batalhoes-menos-em-marica","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/07\/21\/policia-militar-anuncia-abertura-de-tres-novos-batalhoes-menos-em-marica\/","title":{"rendered":"Pol\u00edcia Militar Anuncia Abertura de Tr\u00eas Novos Batalh\u00f5es menos em Maric\u00e1"},"content":{"rendered":"\n<p>De acordo com o Secret\u00e1rio e Comandante Geral da Pol\u00edcia Militar, coronel Marcelo Menezes, a corpora\u00e7\u00e3o ir\u00e1 inaugurar tr\u00eas novos batalh\u00f5es at\u00e9 o final de 2025. No entanto, a cidade de Maric\u00e1 ficou de fora deste an\u00fancio, apesar de ter sido prometida a constru\u00e7\u00e3o de uma nova unidade policial no ano passado.<\/p>\n\n\n\n<p>As novas unidades ser\u00e3o instaladas em:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nova Igua\u00e7u, na Baixada Fluminense<\/li>\n\n\n\n<li>Comunidade do Jacarezinho, na Zona Norte do Rio<\/li>\n\n\n\n<li>S\u00e3o Gon\u00e7alo, onde j\u00e1 existe um batalh\u00e3o atualmente<\/li>\n<\/ul>\n\n\n\n<p>Segundo a Pol\u00edcia Militar, a escolha desses locais se deu ap\u00f3s estudos que apontaram altos \u00edndices de roubos e furtos nessas regi\u00f5es. O novo batalh\u00e3o em S\u00e3o Gon\u00e7alo ir\u00e1 dividir o servi\u00e7o de policiamento do 7\u00ba BPM existente.<\/p>\n\n\n\n<p>Entretanto, o batalh\u00e3o prometido para Maric\u00e1 no ano passado, quando o governador esteve na cidade e assinou o termo para sua constru\u00e7\u00e3o, n\u00e3o foi inclu\u00eddo neste an\u00fancio. De acordo com relatos, a Prefeitura de Maric\u00e1 j\u00e1 cedeu o terreno e realizou a terraplanagem da \u00e1rea, mas at\u00e9 o momento n\u00e3o houve nenhuma movimenta\u00e7\u00e3o por parte do Estado para o in\u00edcio das obras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acordo com o Secret\u00e1rio e Comandante Geral da Pol\u00edcia Militar, coronel Marcelo Menezes, a corpora\u00e7\u00e3o ir\u00e1 inaugurar tr\u00eas novos<\/p>\n","protected":false},"author":1,"featured_media":64633,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[35,14,1],"tags":[],"class_list":["post-64631","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-stories","category-bairros","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/64631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=64631"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/64631\/revisions"}],"predecessor-version":[{"id":64634,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/64631\/revisions\/64634"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/64633"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=64631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=64631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=64631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}