{"id":6510,"date":"2020-01-27T14:14:22","date_gmt":"2020-01-27T17:14:22","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=6510"},"modified":"2020-01-27T14:14:24","modified_gmt":"2020-01-27T17:14:24","slug":"maricaense-flagra-asfalto-se-desfazendo-na-orla-de-itaipuacu","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/01\/27\/maricaense-flagra-asfalto-se-desfazendo-na-orla-de-itaipuacu\/","title":{"rendered":"MARICAENSE FLAGRA ASFALTO SE DESFAZENDO NA ORLA DE ITAIPUA\u00c7U"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82.jpeg\" alt=\"\" class=\"wp-image-6511\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82.jpeg 960w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82-300x300.jpeg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82-150x150.jpeg 150w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82-768x768.jpeg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82-400x400.jpeg 400w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/01\/3F295F53-A81D-4B39-9AF9-39E1B31D2D82-500x500.jpeg 500w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>A Orla da Praia de Itaipua\u00e7u \u00e9 um das obras mais esperadas do bairro nos \u00faltimos anos. Mas um maricaense flagrou o asfalto que \u00e9 novo se desfazendo, chamando a aten\u00e7\u00e3o para a falta de resist\u00eancia do material.<\/p>\n\n\n\n<p>Em uma rede social, a publica\u00e7\u00e3o foi postada em um grupo do bairro que tem mais de 100 mil moradores.<\/p>\n\n\n\n<p>O asfalto na Orla n\u00e3o tem nem dois meses que foi colocado, por isso muitos maricaenses ficaram impressionados.<\/p>\n\n\n\n<p>A urbaniza\u00e7\u00e3o da orla compreende uma via principal com cerca de 8 metros de largura, sendo o cal\u00e7ad\u00e3o com 4,5 metros e uma ciclovia (com 2,30 metros de largura), al\u00e9m de ilumina\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Orla da Praia de Itaipua\u00e7u \u00e9 um das obras mais esperadas do bairro nos \u00faltimos anos. Mas um maricaense<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-6510","post","type-post","status-publish","format-standard","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/6510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=6510"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/6510\/revisions"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=6510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=6510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=6510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}