{"id":66301,"date":"2024-10-27T18:36:20","date_gmt":"2024-10-27T21:36:20","guid":{"rendered":"https:\/\/maricatotal.com.br\/site\/?p=66301"},"modified":"2024-10-27T18:36:20","modified_gmt":"2024-10-27T21:36:20","slug":"uniao-de-marica-classifica-nove-sambas-para-semifinal-do-concurso-de-samba-enredo-do-carnaval-2025","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2024\/10\/27\/uniao-de-marica-classifica-nove-sambas-para-semifinal-do-concurso-de-samba-enredo-do-carnaval-2025\/","title":{"rendered":"Uni\u00e3o de Maric\u00e1 classifica nove sambas para semifinal do concurso de samba-enredo do Carnaval 2025"},"content":{"rendered":"\n<p><br><em>Inicialmente com 18 composi\u00e7\u00f5es, metade segue na briga para representar a escola no pr\u00f3ximo ano<\/em><\/p>\n\n\n\n<p>No in\u00edcio da tarde deste domingo (27), a Uni\u00e3o de Maric\u00e1 anunciou os nove sambas-enredo que avan\u00e7aram para a semifinal do concurso que escolher\u00e1 o hino do seu desfile no Carnaval 2025. A escola vai apresentar na S\u00e9rie Ouro o enredo &#8220;O cavalo de Sant\u00edssimo e a coroa do Seu 7&#8221;, desenvolvido pelo carnavalesco Leandro Vieira, que exalta a m\u00e3e de santo Cacilda de Assis e Seu 7 da Lira, Exu festeiro e entidade marcante da umbanda carioca.<\/p>\n\n\n\n<p><em>Conhe\u00e7a os sambas que seguem na disputa:<\/em><\/p>\n\n\n\n<p>Samba 2 \u2013 Vin\u00edcius Santos e cia<br>Samba 4 \u2013 Babby do Cavaco e cia<br>Samba 7 \u2013 Wanderley Monteiro e cia<br>Samba 10 \u2013 Marquinho Paloma e cia<br>Samba 12 \u2013 Alan Adi<br>Samba 13 \u2013 Xande de Pilares e cia<br>Samba 15 \u2013 Claudio Mattos e cia<br>Samba 17 \u2013 Macaco Branco e cia<br>Samba 18 \u2013 Renan G\u00eameo e cia<\/p>\n\n\n\n<p>A semifinal ocorrer\u00e1 na pr\u00f3xima sexta-feira, dia 1\u00ba de novembro, na quadra da escola, no Centro de Maric\u00e1. Em 2025, a agremia\u00e7\u00e3o ser\u00e1 a sexta a cruzar a Sapuca\u00ed na sexta-feira, 28 de fevereiro, em busca do in\u00e9dito acesso ao Grupo Especial.<\/p>\n\n\n\n<p><em>Fotos: Clarildo Menezes\/Prefeitura de Maric\u00e1<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inicialmente com 18 composi\u00e7\u00f5es, metade segue na briga para representar a escola no pr\u00f3ximo ano No in\u00edcio da tarde deste<\/p>\n","protected":false},"author":1,"featured_media":66303,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[1],"tags":[],"class_list":["post-66301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/66301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=66301"}],"version-history":[{"count":1,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/66301\/revisions"}],"predecessor-version":[{"id":66304,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/66301\/revisions\/66304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/66303"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=66301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=66301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=66301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}