{"id":7948,"date":"2020-03-21T17:07:06","date_gmt":"2020-03-21T20:07:06","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=7948"},"modified":"2020-03-30T19:03:42","modified_gmt":"2020-03-30T22:03:42","slug":"prefeitura-cria-cadastro-de-servicos-delivery-para-atendimento-durante-isolamento","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/03\/21\/prefeitura-cria-cadastro-de-servicos-delivery-para-atendimento-durante-isolamento\/","title":{"rendered":"PREFEITURA CRIA CADASTRO DE SERVI\u00c7OS DELIVERY PARA ATENDIMENTO DURANTE ISOLAMENTO"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"http:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/03\/B9FDCA24-F884-4DB7-8F65-4CA782DBD1F1-1024x682.jpeg\" alt=\"\" class=\"wp-image-7949\" srcset=\"https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/03\/B9FDCA24-F884-4DB7-8F65-4CA782DBD1F1-1024x682.jpeg 1024w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/03\/B9FDCA24-F884-4DB7-8F65-4CA782DBD1F1-300x200.jpeg 300w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/03\/B9FDCA24-F884-4DB7-8F65-4CA782DBD1F1-768x512.jpeg 768w, https:\/\/maricatotal.com.br\/site\/wp-content\/uploads\/2020\/03\/B9FDCA24-F884-4DB7-8F65-4CA782DBD1F1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A decis\u00e3o da Prefeitura de limitar o funcionamento e a capacidade, ou de fechar os estabelecimentos comerciais da cidade como medida de preven\u00e7\u00e3o \u00e0 expans\u00e3o do coronav\u00edrus Covid-19 ganhou uma iniciativa que ajudar\u00e1 os comerciantes a manterem seus neg\u00f3cios, gerando emprego e renda. Para&nbsp;facilitar o acesso dos moradores aos servi\u00e7os, a Secretaria de Desenvolvimento Econ\u00f4mico, Com\u00e9rcio, Ind\u00fastria, Petr\u00f3leo e Portos resolveu fazer um levantamento das empresas e profissionais que est\u00e3o realizando a entrega de produtos dessa forma aos clientes.<\/p>\n\n\n\n<p>\u201cNosso intuito \u00e9 ajudar a divulgar por segmento todas as pessoas que est\u00e3o trabalhando com delivery, facilitando a compra e a venda nesse momento delicado\u201d, explica Luciano Leal, subsecret\u00e1rio de Desenvolvimento Econ\u00f4mico, Com\u00e9rcio, Empreendedorismo e Defesa do Consumidor.<\/p>\n\n\n\n<p>O procedimento \u00e9 simples, basta que os respons\u00e1veis pelos estabelecimentos enviem o nome da empresa, o seguimento e telefone de contato para o email Junior.desenvolvimentomarica@gmail.com A listagem completa dos servi\u00e7os ser\u00e1 divulgada posteriormente, para que toda a popula\u00e7\u00e3o tenha acesso ao que \u00e9 oferecido.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A decis\u00e3o da Prefeitura de limitar o funcionamento e a capacidade, ou de fechar os estabelecimentos comerciais da cidade como<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-7948","post","type-post","status-publish","format-standard","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/7948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=7948"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/7948\/revisions"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=7948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=7948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=7948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}