{"id":8571,"date":"2020-04-04T13:12:22","date_gmt":"2020-04-04T16:12:22","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=8571"},"modified":"2020-04-04T14:02:08","modified_gmt":"2020-04-04T17:02:08","slug":"serra-que-liga-marica-a-niteroi-sera-fechada-neste-sabado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/04\/04\/serra-que-liga-marica-a-niteroi-sera-fechada-neste-sabado\/","title":{"rendered":"SERRA QUE LIGA MARIC\u00c1 A NITER\u00d3I SER\u00c1 FECHADA NESTE S\u00c1BADO"},"content":{"rendered":"\n<p>A Prefeitura de Niter\u00f3i inicia neste s\u00e1bado (4) o plano para reduzir a circula\u00e7\u00e3o de pessoas na cidade, como medida de preven\u00e7\u00e3o \u00e0 pandemia do novo coronav\u00edrus.<\/p>\n\n\n\n<p>Com o novo decreto que entra em vigor hoje, a Serra da Tiririca que liga Maric\u00e1 a Niter\u00f3i, munic\u00edpio vizinho, ser\u00e1 fechada. <\/p>\n\n\n\n<p>A medida foi tomada devido a pandemia do novo coronav\u00edrus, que est\u00e1 afetando a cidade vizinha que tem diversos casos.<\/p>\n\n\n\n<p>Ser\u00e3o montados bloqueios em 28 pontos de acesso a Niter\u00f3i &#8211; em sete deles, haver\u00e1 controle por agentes de tr\u00e2nsito e das for\u00e7as de seguran\u00e7a p\u00fablica.&nbsp;<\/p>\n\n\n\n<p>Niter\u00f3i conta com 65 casos confirmados e 1 \u00f3bito do Covid-19.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Niter\u00f3i inicia neste s\u00e1bado (4) o plano para reduzir a circula\u00e7\u00e3o de pessoas na cidade, como medida<\/p>\n","protected":false},"author":1,"featured_media":8572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-8571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=8571"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/8572"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=8571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=8571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=8571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}