{"id":8582,"date":"2020-04-04T17:59:02","date_gmt":"2020-04-04T20:59:02","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=8582"},"modified":"2020-04-04T17:59:04","modified_gmt":"2020-04-04T20:59:04","slug":"niteroi-tem-a-segunda-morte-confirmada-por-coronavirus","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/04\/04\/niteroi-tem-a-segunda-morte-confirmada-por-coronavirus\/","title":{"rendered":"NITER\u00d3I TEM A SEGUNDA MORTE CONFIRMADA POR CORONAV\u00cdRUS"},"content":{"rendered":"\n<p>Boletim divulgado pela Secretaria de Estado de Sa\u00fade do Rio de Janeiro neste s\u00e1bado (4), j\u00e1 s\u00e3o 1.246 casos confirmados e 58 \u00f3bitos por coronav\u00edrus (Covid-19) no estado. H\u00e1 ainda 72 \u00f3bitos em investiga\u00e7\u00e3o.<\/p>\n\n\n\n<p>Somente hoje, foram confirmados mais onze \u00f3bitos por coronav\u00edrus no estado, totalizando 58, sendo a segunda v\u00edtima do munic\u00edpio de Niter\u00f3i, a primeira de Maric\u00e1, e as outras de Duque de Caxias, Belford Roxo, Mesquita, Nova Igua\u00e7u e capital.<\/p>\n\n\n\n<p>Mulher de 36 anos; de Belford Roxo<\/p>\n\n\n\n<p>Mulher de 52 anos; de Duque de Caxias<\/p>\n\n\n\n<p>Mulher de 53 anos; de Duque de Caxias<\/p>\n\n\n\n<p>Mulher de 80 anos; de Duque de Caxias<\/p>\n\n\n\n<p>Mulher de 67 anos; de Maric\u00e1<\/p>\n\n\n\n<p>Homem de 37 anos; de Mesquita<\/p>\n\n\n\n<p>Mulher de 65 anos; de Niter\u00f3i<\/p>\n\n\n\n<p>Homem de 23 anos; de Nova Igua\u00e7u<\/p>\n\n\n\n<p>Mulher de 55 anos; de Nova Igua\u00e7u<\/p>\n\n\n\n<p>Mulher de 48 anos; do Rio de Janeiro<\/p>\n\n\n\n<p>Homem de 51 anos; do Rio de Janeiro<\/p>\n\n\n\n<p><strong>Os \u00f3bitos dos 31 homens e 27 mulheres foram registrados nos seguintes munic\u00edpios:<\/strong><\/p>\n\n\n\n<p>Rio de Janeiro \u2013 38<\/p>\n\n\n\n<p>Duque de Caxias \u2013 3<\/p>\n\n\n\n<p>Niter\u00f3i \u2013 2<\/p>\n\n\n\n<p>Nova Igua\u00e7u \u2013 2<\/p>\n\n\n\n<p>Volta Redonda \u2013 2<\/p>\n\n\n\n<p>Arraial do Cabo \u2013 1<\/p>\n\n\n\n<p>Belford Roxo \u2013 1<\/p>\n\n\n\n<p>Maric\u00e1 \u2013 1<\/p>\n\n\n\n<p>Mesquita \u2013 1<\/p>\n\n\n\n<p>Miguel Pereira \u2013 1<\/p>\n\n\n\n<p>Petr\u00f3polis \u2013 1<\/p>\n\n\n\n<p>Rio Bonito \u2013 1<\/p>\n\n\n\n<p>Rio das Ostras \u2013 1<\/p>\n\n\n\n<p>S\u00e3o Gon\u00e7alo \u2013 1<\/p>\n\n\n\n<p>S\u00e3o Jo\u00e3o de Meriti \u2013 1<\/p>\n\n\n\n<p><strong>Os casos confirmados at\u00e9 o momento est\u00e3o distribu\u00eddos da seguinte maneira:<\/strong><\/p>\n\n\n\n<p>Rio de Janeiro \u2013 982<\/p>\n\n\n\n<p>Niter\u00f3i \u2013 79<\/p>\n\n\n\n<p>Volta Redonda \u2013 45<\/p>\n\n\n\n<p>Nova Igua\u00e7u \u2013 19<\/p>\n\n\n\n<p>Duque de Caxias \u2013 13<\/p>\n\n\n\n<p>Itabora\u00ed \u2013 13<\/p>\n\n\n\n<p>Petr\u00f3polis \u2013 13<\/p>\n\n\n\n<p>S\u00e3o Gon\u00e7alo \u2013 10<\/p>\n\n\n\n<p>Belford Roxo \u2013 7<\/p>\n\n\n\n<p>Maric\u00e1 \u2013 7<\/p>\n\n\n\n<p>Maca\u00e9 \u2013 6<\/p>\n\n\n\n<p>Mag\u00e9 \u2013 5<\/p>\n\n\n\n<p>S\u00e3o Jo\u00e3o de Meriti \u2013 4<\/p>\n\n\n\n<p>Teres\u00f3polis \u2013 4<\/p>\n\n\n\n<p>Barra Mansa \u2013 3<\/p>\n\n\n\n<p>Rio das Ostras \u2013 3<\/p>\n\n\n\n<p>Angra dos Reis \u2013 2<\/p>\n\n\n\n<p>Barra do Pira\u00ed \u2013 2<\/p>\n\n\n\n<p>Guapimirim \u2013 2<\/p>\n\n\n\n<p>Itagua\u00ed \u2013 2<\/p>\n\n\n\n<p>Mangaratiba \u2013 2<\/p>\n\n\n\n<p>Para\u00edba do Sul \u2013 2<\/p>\n\n\n\n<p>Queimados \u2013 2<\/p>\n\n\n\n<p>Resende \u2013 2<\/p>\n\n\n\n<p>Rio Bonito \u2013 2<\/p>\n\n\n\n<p>Valen\u00e7a \u2013 2<\/p>\n\n\n\n<p>Araruama \u2013 1<\/p>\n\n\n\n<p>Arraial do Cabo \u2013 1<\/p>\n\n\n\n<p>Campos dos Goytacazes \u2013 1<\/p>\n\n\n\n<p>Iguaba Grande \u2013 1<\/p>\n\n\n\n<p>Miguel Pereira \u2013 1<\/p>\n\n\n\n<p>Mesquita \u2013 1<\/p>\n\n\n\n<p>Nil\u00f3polis \u2013 1<\/p>\n\n\n\n<p>Nova Friburgo \u2013 1<\/p>\n\n\n\n<p>Porci\u00fancula \u2013 1<\/p>\n\n\n\n<p>S\u00e3o Pedro da Aldeia \u2013 1<\/p>\n\n\n\n<p>Serop\u00e9dica \u2013 1<\/p>\n\n\n\n<p>Tr\u00eas Rios \u2013 1<\/p>\n\n\n\n<p>Munic\u00edpio de resid\u00eancia em investiga\u00e7\u00e3o \u2013 1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boletim divulgado pela Secretaria de Estado de Sa\u00fade do Rio de Janeiro neste s\u00e1bado (4), j\u00e1 s\u00e3o 1.246 casos confirmados<\/p>\n","protected":false},"author":1,"featured_media":8583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-8582","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=8582"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/8583"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=8582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=8582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=8582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}