{"id":8673,"date":"2020-04-07T10:26:49","date_gmt":"2020-04-07T13:26:49","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=8673"},"modified":"2020-04-07T10:26:50","modified_gmt":"2020-04-07T13:26:50","slug":"coronavirus-mcmv-de-itaipuacu-e-sanitizado","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/04\/07\/coronavirus-mcmv-de-itaipuacu-e-sanitizado\/","title":{"rendered":"CORONAV\u00cdRUS: MCMV DE ITAIPUA\u00c7U \u00c9 SANITIZADO"},"content":{"rendered":"\n<p>O Residencial Carlos Marighela, o &#8216;Minha Casa, Minha Vida&#8217; de Itaipua\u00e7u foi sanitizado na manh\u00e3 desta ter\u00e7a-feira (7).<\/p>\n\n\n\n<p>Agentes da Sanemix fizeram a sanitiza\u00e7\u00e3o em todas as cal\u00e7adas, quadras, varandas e ruas do condom\u00ednio, que \u00e9 um dos locais mais populosos do munic\u00edpio de Maric\u00e1. <\/p>\n\n\n\n<p> A orienta\u00e7\u00e3o \u00e9 que o produto qu\u00edmico seja dispersado nos locais onde h\u00e1 maior movimenta\u00e7\u00e3o de pessoas. O processo sanit\u00e1rio \u00e9 feito diariamente, duas vezes por dia, em todos os locais.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Residencial Carlos Marighela, o &#8216;Minha Casa, Minha Vida&#8217; de Itaipua\u00e7u foi sanitizado na manh\u00e3 desta ter\u00e7a-feira (7). Agentes da<\/p>\n","protected":false},"author":1,"featured_media":8674,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[14],"tags":[],"class_list":["post-8673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bairros"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=8673"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/8674"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=8673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=8673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=8673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}