{"id":8733,"date":"2020-04-08T12:39:08","date_gmt":"2020-04-08T15:39:08","guid":{"rendered":"http:\/\/maricatotal.com.br\/site\/?p=8733"},"modified":"2020-04-16T23:15:03","modified_gmt":"2020-04-17T02:15:03","slug":"coronavirus-hospital-dr-ernesto-che-guevara-recebe-150-leitos-hospitalares","status":"publish","type":"post","link":"https:\/\/maricatotal.com.br\/site\/2020\/04\/08\/coronavirus-hospital-dr-ernesto-che-guevara-recebe-150-leitos-hospitalares\/","title":{"rendered":"CORONAV\u00cdRUS: HOSPITAL DR. ERNESTO CHE GUEVARA RECEBE 150 LEITOS HOSPITALARES"},"content":{"rendered":"\n<p>O novo Hospital Municipal Dr. Ernesto Che Guevara recebeu 150 leitos hospitalares de \u00faltima gera\u00e7\u00e3o na manh\u00e3 desta quarta-feira (8). A nova unidade est\u00e1 localizada em S\u00e3o Jos\u00e9 do Imbassa\u00ed, e ser\u00e1 inaugurada emergencialmente para combater o Covid-19.<\/p>\n\n\n\n<p>Maric\u00e1 vai se prevenindo cada dia mais contra o coronav\u00edrus. 150 leitos hospitalares j\u00e1 est\u00e3o sendo instalados no novo Hospital para funcionar caso algum paciente fique em estado mais grave.<\/p>\n\n\n\n<p>Al\u00e9m dos leitos, a unidade receber\u00e1 50 macas para transfer\u00eancia de pacientes para o local.<\/p>\n\n\n\n<p>O Hospital Dr. Ernesto Che Guevara ainda n\u00e3o tem data para inaugurar, mas a cada dia se aproxima. Cerca de 99% das obras j\u00e1 est\u00e3o conclu\u00eddas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O novo Hospital Municipal Dr. Ernesto Che Guevara recebeu 150 leitos hospitalares de \u00faltima gera\u00e7\u00e3o na manh\u00e3 desta quarta-feira (8).<\/p>\n","protected":false},"author":1,"featured_media":8734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[18],"tags":[],"class_list":["post-8733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimento"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/comments?post=8733"}],"version-history":[{"count":0,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/posts\/8733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media\/8734"}],"wp:attachment":[{"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/media?parent=8733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/categories?post=8733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maricatotal.com.br\/site\/wp-json\/wp\/v2\/tags?post=8733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}